{"id":23531,"date":"2013-06-17T15:04:18","date_gmt":"2013-06-17T13:04:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23531"},"modified":"2023-01-17T13:21:05","modified_gmt":"2023-01-17T12:21:05","slug":"9362-diciannovenne-muore-per-congestione-dopo-un-tuffo-in-mare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9362-diciannovenne-muore-per-congestione-dopo-un-tuffo-in-mare\/","title":{"rendered":"Diciannovenne muore per congestione tra l&#8217;indifferenza dei bagnanti"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Un bagno rinfrescante trasformatosi in tragedia.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Un giovane di nazionalita&#8217; marocchina, Abdur Abderhaman, 19 anni, e&#8217; deceduto a causa di una congestione mentre stava facendo il bagno nelle acque antistanti la spiaggia di Vibo Marina nei pressi di via Amerigo Vespucci, a pochi metri dalla sede dei Vigili del fuoco. Prontamente soccorso da alcuni bagnanti e dai medici del 118 per il ragazzo non c&#8217;e&#8217; stato pero&#8217; nulla da fare. Sull&#8217;episodio indaga la polizia e la Guardia costiera, supportati dal medico legale, Katiuscia Bisogni. Il dramma della morte del giovane ha rivelato uno spaccatto agghiacciante della societ\u00e0 italiana moderna: l&#8217;indifferenza verso il prossimo. Sul bagnasciuga infatti mentre capitaneria di porto e carabinieri attendevano l&#8217;arrivo del legale per la constatazione del decesso davanti al corpo esanime del 19enne poco distante un gruppo di ragazzi avrebbe continuato a disputare la propria partita a calcetto ignorando la presenza del cadavere del coetaneo. Altri bagnanti invece non avrebbero esitato a proseguire la propria giornata continuando a prendere tranquillamente il sole nonostante a pochi metri si stesse consumando il macabro episodio. Una storia di indifferenza diffusa e di scarso senso di solidariet\u00e0 che ha avuto termine solo quando uno tra gli astanti disgustato da tanta indolenza avrebbe protestato tra gli ombrelloni chiedendo a gran voce di porre fine a tanta normalit\u00e0 facendo notare la presenza della salma del ragazzino.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Il leader del Movimento Diritti Civili, Franco Corbelli, interviene &#8220;sulla tragedia del giovane immigrato marocchino, Abdur Abderhaman, 19 anni, morto affogato ieri nel mare di Vibo Marina, e una volta portato a riva e coperto con un lenzuolo, letteralmente ignorato dai bagnanti che hanno continuato a tuffarsi in acqua e a giocare sulla spiaggia&#8221;. Corbelli parla di &#8220;un brutto spettacolo, contrario ai piu&#8217; elementari principi di umanita&#8217; e solidarieta&#8217;&#8221; e rivolge un appello al sindaco di Vibo, Nicola D&#8217;Agostino, che &#8220;invita a chiedere scusa a nome della civilissima citta&#8217; di Vibo per quanto accaduto sulla spiaggia e a farsi carico, come comune, delle spese del funerale e del trasporto in Marocco della salma del giovane, sfortunato immigrato&#8221;. Il leader di Diritti Civili afferma di &#8220;essere pronto, cosi&#8217; come ha gia&#8217; fatto in passato per altri casi di immigrati deceduti e rimasti per molti giorni nell&#8217;obitorio degli ospedali di Cosenza(un altro marocchino morto in un incidente a Luzzi) e di Cetraro (un rumeno morto annegato a Paola), a contribuire personalmente alle spese per il funerale e il trasporto della bara in Marocco. &#8220;Quanto accaduto sulla spiaggia di Vibo &#8211; dice &#8211; e&#8217; un fatto molto grave, assolutamente inaccettabile, che non puo&#8217; passare in silenzio o essere subito archiviato, come se nulla fosse successo. Quel ragazzo morto, coperto da un lenzuolo, ignorato dai bagnanti e&#8217; qualcosa di molto grave che deve far riflettere tutti. Coloro i quali hanno ignorato quel giovane immigrato morto hanno commesso un gravissimo errore. Spero che se ne siano resi conto e siano i primi pentirsi di quello che hanno fatto. La civilissima citta&#8217; di Vibo non e&#8217; certo quella rappresentata ieri sulla spiaggia davanti a quel corpo senza vita di quel povero, sfortunato immigrato. Per questo invito il sindaco D&#8217;Agostino a chiedere scusa a nome di tutti i suoi concittadini per quanto accaduto. Allo stesso primo cittadino vibonese, che conosco e stimo, chiedo di farsi carico delle spese del funerale e del trasporto della salma del giovane nel suo paese&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Un bagno rinfrescante trasformatosi in tragedia.<\/p>\n","protected":false},"author":22,"featured_media":23532,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-23531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23531"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23532"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}