{"id":235451,"date":"2024-07-19T08:00:59","date_gmt":"2024-07-19T06:00:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=235451"},"modified":"2024-07-19T07:38:17","modified_gmt":"2024-07-19T05:38:17","slug":"bimba-di-un-anno-dimenticata-in-auto-dal-papa-muore-di-caldo-asaps-rilancia-non-dimenticarmi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/bimba-di-un-anno-dimenticata-in-auto-dal-papa-muore-di-caldo-asaps-rilancia-non-dimenticarmi\/","title":{"rendered":"Bimba di un anno dimenticata in auto dal pap\u00e0 muore di caldo. Asaps rilancia &#8220;Non dimenticarmi&#8221;"},"content":{"rendered":"<div id=\"txt_cont\">BOLOGNA &#8211; L&#8217;Asaps-Associazione Sostenitori Amici Polizia Stradale<strong> interviene dopo la tragedia di Marcon (Venezia), dove una bimba di un anno \u00e8 morta di caldo,<\/strong> dimenticata in auto dal pap\u00e0, e attraverso il proprio sito rilancia la campagna &#8216;Non dimenticarmi&#8217;.<br \/>\n&#8220;Ogni anno nel mondo e anche nel nostro Paese &#8211; ricorda il presidente Giordano Biserni &#8211; assistiamo <strong>ad episodi particolarmente gravi in cui muoiono centinaia di bambini, a causa di colpi di calore a bordo di veicoli chiusi<\/strong>, al cui interno vengono dimenticati figli o nipoti, oppure perch\u00e9 gli stessi giocando hanno inavvertitamente chiuso il mezzo, rimanendovi intrappolati&#8221;.<\/div>\n<div><\/div>\n<div>Negli Stati Uniti nel 2023 sono morti 29 bambini, nel solo 2024 sono gi\u00e0 13, tre solo fra il 14 e il 16 luglio negli stati di New York, New Jersey e Illinois.<strong>&#8220;Le tragedie familiari &#8211; aggiunge l&#8217;Asaps &#8211; sono immense, il dolore della perdita di un figlio si trasforma spesso in profonde crisi psicologiche di una famiglia che continua a vivere nel rimorso e spesso se ne esce solamente creando associazioni<\/strong> che iniziano a sensibilizzare sul delicato tema della salute dei nostri bimbi&#8221;.Asaps, da sempre attenta ai problemi connessi alla sicurezza sulle strade italiane, nell&#8217;imminenza delle grandi partenze estive ricorda anche che &#8220;vige l&#8217;obbligo del seggiolino antiabbandono, con sanzioni pesanti&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>BOLOGNA &#8211; L&#8217;Asaps-Associazione Sostenitori Amici Polizia Stradale interviene dopo la tragedia di Marcon (Venezia), dove una bimba di un anno \u00e8 morta di caldo, dimenticata in auto dal pap\u00e0, e attraverso il proprio sito rilancia la campagna &#8216;Non dimenticarmi&#8217;. &#8220;Ogni anno nel mondo e anche nel nostro Paese &#8211; ricorda il presidente Giordano Biserni &#8211; [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":235452,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-235451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=235451"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/235452"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=235451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=235451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=235451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}