{"id":235599,"date":"2024-07-20T11:43:23","date_gmt":"2024-07-20T09:43:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=235599"},"modified":"2024-07-20T11:43:23","modified_gmt":"2024-07-20T09:43:23","slug":"sotto-sequestro-un-depuratore-dismesso-i-reflui-finivano-nel-canale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sotto-sequestro-un-depuratore-dismesso-i-reflui-finivano-nel-canale\/","title":{"rendered":"Sotto sequestro un depuratore dismesso, i reflui finivano nel canale"},"content":{"rendered":"<p>SQUILLACE (CZ) &#8211; Il depuratore di acque reflue del comune di Squillace, all&#8217;ispezione degli investigatori \u00e8 <strong>risultato completamente demolito<\/strong>. I militari del Nucleo operativo di Polizia ambientale dell&#8217;Ufficio circondariale marittimo di Soverato lo hanno sequestrato perch\u00e8, nonostante non fosse funzionante, secondo quanto accertato, <strong>i reflui continuavano ad arrivare all&#8217;interno<\/strong> dello stesso per poi essere scaricati in un vicino canale senza subire alcun processo depurativo.<\/p>\n<p>L&#8217;impianto \u00e8 stato dunque posto sotto sequestro penale e sono state formulate le ipotesi di reato di mancata osservazione del divieto di scarico e abbandono di rifiuti sul suolo e nelle acque superficiali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SQUILLACE (CZ) &#8211; Il depuratore di acque reflue del comune di Squillace, all&#8217;ispezione degli investigatori \u00e8 risultato completamente demolito. I militari del Nucleo operativo di Polizia ambientale dell&#8217;Ufficio circondariale marittimo di Soverato lo hanno sequestrato perch\u00e8, nonostante non fosse funzionante, secondo quanto accertato, i reflui continuavano ad arrivare all&#8217;interno dello stesso per poi essere scaricati [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":235600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-235599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=235599"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/235600"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=235599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=235599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=235599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}