{"id":235842,"date":"2024-07-23T21:30:35","date_gmt":"2024-07-23T19:30:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=235842"},"modified":"2024-07-23T20:28:42","modified_gmt":"2024-07-23T18:28:42","slug":"stretta-dei-carabinieri-nelle-zone-della-movida-fioccano-sanzioni-e-denunce","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/stretta-dei-carabinieri-nelle-zone-della-movida-fioccano-sanzioni-e-denunce\/","title":{"rendered":"Stretta dei carabinieri nelle zone della movida: fioccano sanzioni e denunce"},"content":{"rendered":"<p>SOVERATO &#8211; Continuano i controlli dei Carabinieri della Compagnia di Soverato su tutto il territorio di competenza, nell\u2019ambito dell\u2019operazione \u201c<strong>Estate in Sicurezza 2024<\/strong>\u201d. Le attivit\u00e0 dei militari hanno interessato principalmente le zone della movida, anche con pattuglie a piedi, con l\u2019obiettivo di prevenire e reprimere lo spaccio di droga.\u00a0<strong>Un 19enne \u00e8 stato trovato in possesso di una dose di marijuana<\/strong>\u00a0e segnalato in Prefettura come assuntore, cos\u00ec come\u00a0<strong>due 24enni\u00a0<\/strong>della zona sono stati\u00a0<strong>sorpresi ciascuno con un involucro di cocaina<\/strong>, per complessivi 1,00 grammo, che alla vista dei militari hanno tentato di disfarsi. Un\u00a0<strong>40enne \u00e8 stato trovato nella disponibilit\u00e0 di due flaconi di metadone<\/strong>.<\/p>\n<p>Non sono mancate le verifiche alla circolazione stradale, per contrastare le condotte di guida pericolose e irresponsabili. Complessivamente sono stati identificati 360 tra conducenti e passeggeri, controllati 249 veicoli. <strong>Pi\u00f9 di 50 gli automobilisti multati per un totale di 6.782 euro e 35 punti sottratti<\/strong>, soprattutto per guida senza far uso delle cinture di sicurezza e con telefono cellulare senza far uso di auricolari. Un giovane, corso controllo alla circolazione stradale a Soverato, alla guida di un\u2019autovettura, in\u00a0<strong>evidente stato di alterazione psicofisica<\/strong>, sottoposto ad accertamento con alcoltest in dotazione dai militari della Sezione Radiomobile, \u00e8 risultato positivo all\u2019etanolo per un valore pari a 0,6 g\/l.\u00a0<strong>La patente di guida \u00e8 stata ritirata<\/strong>.<\/p>\n<p>Sempre a Soverato, un uomo \u00e8 stato fermato alla guida di un veicolo, importato dall\u2019estero, con <strong>targhe, documenti di immatricolazione e assicurativi risultati tutti falsi<\/strong>.<br \/>\nNell\u2019ambito delle attivit\u00e0 finalizzate al\u00a0<strong>contrasto della vendita di prodotti alimentari senza il rispetto dei requisiti minimi previsti dalle norme igienico-sanitarie<\/strong>\u00a0e alla tutela della salute dei numerosissimi vacanzieri e residenti della zona, i controlli dei Carabinieri della Compagnia di Soverato hanno permesso di rinvenire\u00a0<strong>14 kg di pane e altri 4 kg di prodotti da forno all\u2019interno di un\u2019autovettura<\/strong>. Il conducente del mezzo, che ha omesso di predisporre procedure di autocontrollo basate sui principi del\u00a0<strong>sistema Haccp e con prodotti in assenza di tracciabilit\u00e0<\/strong>, \u00e8 stato sanzionato dai militari, unitamente a personale dell\u2019Asp, per complessivi 4.000,00 euro, per violazione degli obblighi in materia di sicurezza alimentare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SOVERATO &#8211; Continuano i controlli dei Carabinieri della Compagnia di Soverato su tutto il territorio di competenza, nell\u2019ambito dell\u2019operazione \u201cEstate in Sicurezza 2024\u201d. Le attivit\u00e0 dei militari hanno interessato principalmente le zone della movida, anche con pattuglie a piedi, con l\u2019obiettivo di prevenire e reprimere lo spaccio di droga.\u00a0Un 19enne \u00e8 stato trovato in possesso [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":149631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-235842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=235842"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/149631"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=235842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=235842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=235842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}