{"id":235967,"date":"2024-07-24T17:00:35","date_gmt":"2024-07-24T15:00:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=235967"},"modified":"2024-07-24T16:42:13","modified_gmt":"2024-07-24T14:42:13","slug":"scontro-tra-due-auto-sulla-statale-106-traffico-bloccato-foto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/scontro-tra-due-auto-sulla-statale-106-traffico-bloccato-foto\/","title":{"rendered":"Scontro tra due auto sulla Statale 106: traffico bloccato &#8211; FOTO"},"content":{"rendered":"<p>SELLIA MARINA (CZ) &#8211; Incidente nel primo pomeriggio di oggi <strong>sulla Strada Statale 106 in localit\u00e0 La Patrizia di Sellia Marina in provincia di Catanzaro<\/strong>. Coinvolte nel sinistro due autovetture tra una Marcedes \u00e8 una Toyota Yaris.<\/p>\n<p>Traffico rallentato danni ingenti ai mezzi <strong>ma secondo le prime notizie nessun ferito grave.<\/strong> Sul posto Carabinieri di Sellia Marina per gli accertamenti di competenza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-235969 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-sellia.jpg\" alt=\"\" width=\"576\" height=\"311\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-sellia.jpg 972w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-sellia-300x162.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-sellia-768x415.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-sellia-778x420.jpg 778w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-sellia-150x81.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-sellia-696x376.jpg 696w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SELLIA MARINA (CZ) &#8211; Incidente nel primo pomeriggio di oggi sulla Strada Statale 106 in localit\u00e0 La Patrizia di Sellia Marina in provincia di Catanzaro. Coinvolte nel sinistro due autovetture tra una Marcedes \u00e8 una Toyota Yaris. Traffico rallentato danni ingenti ai mezzi ma secondo le prime notizie nessun ferito grave. Sul posto Carabinieri di [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":235968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-235967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=235967"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/235968"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=235967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=235967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=235967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}