{"id":23646,"date":"2013-06-20T12:56:44","date_gmt":"2013-06-20T10:56:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23646"},"modified":"2023-01-17T13:21:13","modified_gmt":"2023-01-17T12:21:13","slug":"9419-incendio-auto-datore-lavoro-a-bolzano-arrestato-in-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9419-incendio-auto-datore-lavoro-a-bolzano-arrestato-in-calabria\/","title":{"rendered":"Incendio&#8217; auto datore lavoro a bolzano, arrestato in Calabria"},"content":{"rendered":"<p style=\"text-align: justify;\">LAMEZIA TERME (CATANZARO) &#8211; Un uomo di 40 anni, Giuseppe Torcasio, di Lamezia Terme, e&#8217; stato arrestato dalla Polizia di Stato che ha eseguito<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">un provvedimento, emesso dalla Procura di Bolzano, di revoca del decreto di sospensione dell&#8217;ordine di carcerazione e ripristino dell&#8217;ordine stesso: l&#8217;uomo, noto alle forze dell&#8217;ordine, e&#8217; accusato di aver provocato un incendio e deve espiare la relativa condanna.&nbsp;<br \/>I fatti contestati risalgono al 12 settembre del 2009 periodo in cui L&#8217;uomo risiedeva a Bolzano. Torcasio, nottetempo, avrebbe incendiato aun&#8217;autovettura di proprieta&#8217; dell&#8217;ex datore di lavoro, proprietario di un hotel, parcheggiata proprio nel piazzale dell&#8217;albergo. Il rogo danneggio&#8217; anche un furgone. Ad incastrare l&#8217;autore del gesto le telecamere presenti nel piazzale e il riconoscimento da parte dei proprietari con i quali lo stesso aveva avuto rapporti molto conflittuali. &nbsp;Dopo le formalita&#8217; di rito Torcasio e&#8217; stato condotto presso il carcere cittadino per espiare una pena residua di 2 anni e 3 mesi di reclusione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAMEZIA TERME (CATANZARO) &#8211; Un uomo di 40 anni, Giuseppe Torcasio, di Lamezia Terme, e&#8217; stato arrestato dalla Polizia di Stato che ha eseguito<\/p>\n","protected":false},"author":22,"featured_media":23647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-23646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23646"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23647"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}