{"id":236531,"date":"2024-07-30T16:45:52","date_gmt":"2024-07-30T14:45:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=236531"},"modified":"2024-07-30T16:47:57","modified_gmt":"2024-07-30T14:47:57","slug":"pd-cosenza-sospeso-il-provvedimento-di-espulsione-per-tinto-graziadio-e-trecroci","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/pd-cosenza-sospeso-il-provvedimento-di-espulsione-per-tinto-graziadio-e-trecroci\/","title":{"rendered":"Pd Cosenza: sospeso il provvedimento di espulsione per Tinto, Graziadio e Trecroci"},"content":{"rendered":"<p>COSENZA &#8211;<strong> Gianfranco Tinto, Francesco Graziadio e Aldo Trecroci, sono i tre consiglieri dissidenti di Palazzo dei Bruzi che qualche settimana fa furono <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/cosenza\/dissidenti-dem-a-palazzo-dei-bruzi-espulsi-dal-pd-graziadio-tinto-e-trecroci\" target=\"_blank\" rel=\"noopener\">espulsi<\/a> dal Partito Democratico, <\/strong>rei di aver costituito a Palazzo dei Bruzi un nuovo gruppo consiliare uscendo da quello del Pd, dove erano stati eletti nel 2021, nella coalizione di centrosinistra che ha eletto sindaco di Cosenza, Franz Caruso, restando per\u00f2 iscritti al Partito Democratico. A decretarne tale espulsione fu <strong>la commissione di garanzia provinciale del Pd di Cosenza, <\/strong>presieduta dall\u2019ex sindaco\u00a0<strong>Salvatore Perugini<\/strong>,\u00a0<strong>dal Partito Democratico cosentino.<\/strong><\/p>\n<p>Oggi la notizia:<strong> il provvedimento di espulsione dei tre consiglieri comunali \u00e8 stato sospeso.\u00a0<\/strong>I tre consiglieri comunali di Cosenza <strong>avevano presentato ricorso alla Commissione di Garanzia Regionale<\/strong>, ovviamente sempre del Pd.<\/p>\n<p>Per il consigliere comunale <strong>Gianfranco Tinto,<\/strong> <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/espulsi-dal-pd-di-cosenza-tinto-graziadio-e-trecroci-ricorrono-alla-commissione-di-garanzia-regionale\" target=\"_blank\" rel=\"noopener\">dichiar\u00f2<\/a> a QuiCosenza, che l\u2019espulsione decretata dalla Commissione di Garanzia Provinciale del Pd, fu una vera e propria sorpresa, \u201cperch\u00e9 interpretando lo Statuto del Partito, q<strong>uesta commissione avrebbe dovuto sospendere ogni attivit\u00e0, in seguito alle dimissioni di ben tre componenti<\/strong>\u201d. D\u2019altro proprio la segretaria nazionale <strong>Elly Schlein<\/strong> non avrebbe \u201cgradito\u201d il provvedimento eseguito nei confronti dei tre consiglieri comunali.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Gianfranco Tinto, Francesco Graziadio e Aldo Trecroci, sono i tre consiglieri dissidenti di Palazzo dei Bruzi che qualche settimana fa furono espulsi dal Partito Democratico, rei di aver costituito a Palazzo dei Bruzi un nuovo gruppo consiliare uscendo da quello del Pd, dove erano stati eletti nel 2021, nella coalizione di centrosinistra che [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":226623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-236531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/236531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=236531"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/236531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/226623"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=236531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=236531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=236531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}