{"id":236638,"date":"2024-08-01T06:50:47","date_gmt":"2024-08-01T04:50:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=236638"},"modified":"2024-08-01T07:16:58","modified_gmt":"2024-08-01T05:16:58","slug":"abramo-customer-care-fibercop-risponde-al-sindacato-contratto-prorogato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/abramo-customer-care-fibercop-risponde-al-sindacato-contratto-prorogato\/","title":{"rendered":"Abramo Customer Care, Fibercop risponde al sindacato \u00abcontratto prorogato\u00bb"},"content":{"rendered":"<p>CATANZARO &#8211; FiberCop risponde a seguito dell&#8217;allarme lanciato dal sindacato Slc Cgil e comunica &#8220;di aver inviato ad Abramo Customer Care la comunicazione riguardante la proroga del contratto&#8221;.<\/p>\n<p>L&#8217;azienda ha rassicurato &#8220;smentendo quindi quanto <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/ennesima-tegola-nella-vertenza-abramo-fibercop-revoca-i-volumi\">comunicato dalla Slc-Cgil&#8221;.<\/a> FiberCop, al riguardo, &#8220;sottolinea di aver gi\u00e0 inviato ad Abramo la programmazione delle attivit\u00e0 previste per il mese di agosto relative all&#8217;assistenza tecnica del servizio 187 di Tim&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; FiberCop risponde a seguito dell&#8217;allarme lanciato dal sindacato Slc Cgil e comunica &#8220;di aver inviato ad Abramo Customer Care la comunicazione riguardante la proroga del contratto&#8221;. L&#8217;azienda ha rassicurato &#8220;smentendo quindi quanto comunicato dalla Slc-Cgil&#8221;. FiberCop, al riguardo, &#8220;sottolinea di aver gi\u00e0 inviato ad Abramo la programmazione delle attivit\u00e0 previste per il mese [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":162317,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-236638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/236638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=236638"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/236638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/162317"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=236638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=236638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=236638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}