{"id":23668,"date":"2013-06-21T05:54:12","date_gmt":"2013-06-21T03:54:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23668"},"modified":"2023-01-17T13:21:15","modified_gmt":"2023-01-17T12:21:15","slug":"9430-l-arte-contemporanea-contamina-cosenza-c-e-art-in-progress","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9430-l-arte-contemporanea-contamina-cosenza-c-e-art-in-progress\/","title":{"rendered":"L&#8217;arte contemporanea contamina Cosenza: c&#8217;e&#8217; &#8220;Art in Progress&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">COSENZA &#8211; Un pubblico vasto e composito ha riempito il centro storico della citta\u2019 di Cosenza partecipando con viva attenzione alle prime tre giornate della seconda edizione di Art in Progress-Festival di Arte contemporanea.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Una settimana, quella appena trascorsa, ricca di contaminazioni culturali: incontri con artisti di levatura internazionale come J<strong>im Avignon<\/strong> hanno dialogato con Minia, performances di poesia sonora e musica contemporanea a cura del <strong>Conservatorio Giacomantonio di Cosenza<\/strong> e <strong>Urban body experience<\/strong>; l&#8217;arte pop di <strong>Urban Superstar<\/strong> e le sue due mostre Suggestivism, The New Horizon a cura di Nathan Spoor e City Of Women a cura di David Vecchiato con l&#8217;interdisciplinarieta\u2019 di ARTE = VITA: ovvero, una vita vissuta ad arte\u2028a cura di <strong>Dores Sacquegna<\/strong>.<br \/>La citta\u2019 di Cosenza e\u2019 stata invasa dalla portata emozionale de Le Canzoni Invisibili a cura di <strong>Lagash, gia\u2019 bassista dei Marlene Kuntz<\/strong>, e <strong>Sinatti<\/strong> e dalle fascinazioni delle parole dell&#8217;attrice <strong>Francesca Beggio<\/strong> che ha regalato la sua voce a I Sogni di Fellini, unendo la sua forza espressiva alla carica di suono delle musiche a cura del \u201cConservatorio S. Giacomantonio\u201d.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Mentre restano visitabili ogni giorno le mostre in programma (basta consultare il sito <a href=\"http:\/\/www.artinprogress.it\" target=\"_blank\" rel=\"noopener\">www.artinprogress.it<\/a> per info e dettagli), oggi alle ore 18, presso la Galleria Provinciale di Santa Chiara, <strong>si terra\u2019 l&#8217;apertura della mostra Minia<\/strong>: installazioni sonoro-visuali a cura del MENTE (Musica Elettronica e Nuove Tecnologie Ensemble) che restera\u2019 aperta fino al 19 luglio\u2028da marted\u00ec a domenica dalle 10.00 alle 13.00 e dalle 16.00 alle 20.00; alle ore 21.00 in Piazza Duomo, sempre nell&#8217;ambito del progetto MINIA, ci sar\u00e0 un&#8217;attesa performance dal titolo Cage Open Air &#8211; Arte sonora negli spazi urbani.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Di seguito il programma di oggi venerdi\u2019 21:<br \/>Galleria Provinciale di Santa Chiara, ore 18.00 &#8211;&nbsp;Apertura mostra MINIA (installazioni sonoro visuali a cura del MENTE)<\/p>\n<p style=\"text-align: justify;\">P.zza Duomo, ore 21.00 &#8211;&nbsp;MINIA \u2013 performance Cage Open Air &#8211; Arte sonora negli spazi urbani<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">PER INFO: <a href=\"http:\/\/www.artinprogress.it\" target=\"_blank\" rel=\"noopener\">www.artinprogress.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Un pubblico vasto e composito ha riempito il centro storico della citta\u2019 di Cosenza partecipando con viva attenzione alle prime tre giornate della seconda edizione di Art in Progress-Festival di Arte contemporanea.&nbsp;<\/p>\n","protected":false},"author":22,"featured_media":23669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-23668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23668"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23669"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}