{"id":236766,"date":"2024-08-02T11:00:08","date_gmt":"2024-08-02T09:00:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=236766"},"modified":"2024-08-02T10:41:37","modified_gmt":"2024-08-02T08:41:37","slug":"sala-giochi-con-accesso-segreto-sanzione-da-un-milione-e-mezzo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sala-giochi-con-accesso-segreto-sanzione-da-un-milione-e-mezzo\/","title":{"rendered":"Sala giochi con accesso segreto, sanzione da un milione e mezzo"},"content":{"rendered":"<p>RIZZICONI &#8211; Nell\u2019ambito di un servizio di controllo del territorio finalizzato al contrasto del gioco illegale, i militari della Stazione di Rizziconi, congiuntamente ai funzionari dell\u2019Agenzia delle Dogane e dei Monopoli (ADM), hanno effettuato verifiche all\u2019interno <strong>un bar di Rizziconi nel quale gi\u00e0 erano state elevate sanzioni per quasi un milione di euro<\/strong>. Non pago della sanzione gi\u00e0 ottenuta nel maggio di quest\u2019anno, il titolare del bar non ha adottato nel frattempo le misure necessarie a regolarizzare l\u2019attivit\u00e0, perseverando nella sua condotta illecita.<\/p>\n<p><strong>Nonostante il primo sequestro delle quattro slot machine, infatti, il proprietario ne ha ricomprate quattro nuove e ha costruito un muro di cartongesso nel suo locale<\/strong>\u00a0per occultare alla vista l\u2019ala adibita a \u201csala giochi\u201d nell\u2019illusione che, murando l\u2019accesso principale alla stanza, avrebbe eluso i controlli. Nel corso dell\u2019intervento congiunto, l\u2019ADM e i Carabinieri di Rizziconi hanno per\u00f2 immediatamente constatato una situazione del tutto analoga a quella di qualche mese fa. Infatti, all\u2019interno del locale vi era una vera e propria sala giochi abusiva, con quattro slot machine perfettamente funzionanti e maldestramente occultate.\u00a0<strong>L\u2019accesso \u201csegreto\u201d era nascosto da un quadro affisso alla parete che dava su una porta resa difficilmente visibile a causa della tinteggiatura identica al resto del muro<\/strong>.<\/p>\n<p>A seguito degli accertamenti \u00e8 stata appurata l\u2019assenza dell\u2019iscrizione all\u2019elenco dei soggetti possessori di apparecchi da intrattenimento, la mancata apposizione della tabella dei giochi proibiti e il mancato pagamento dell\u2019imposta sugli intrattenimenti. <strong>Il titolare \u00e8 stato, inoltre, deferito all\u2019Autorit\u00e0 Giudiziaria in stato di libert\u00e0 per frode informatica<\/strong>, in quanto gli apparecchi, privi di titoli autorizzatori, erano stati verosimilmente fabbricati e programmati per fini di lucro, con relativa scheda di gioco contraffatta al fine di impedire la comunicazione\u00a0online\u00a0delle giocate effettuate e la corretta tassazione delle somme di denaro giocate. Queste irregolarit\u00e0 si aggiungono a quelle gi\u00e0 riscontrate nel precedente accertamento, tra le quali vi \u00e8 anche una maxi-sanzione tributaria per evasione d\u2019imposta. Sommando tutte le sanzioni applicate in questa occasione e in quella precedente,\u00a0<strong>si supera la cifra di un milione e mezzo di euro.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RIZZICONI &#8211; Nell\u2019ambito di un servizio di controllo del territorio finalizzato al contrasto del gioco illegale, i militari della Stazione di Rizziconi, congiuntamente ai funzionari dell\u2019Agenzia delle Dogane e dei Monopoli (ADM), hanno effettuato verifiche all\u2019interno un bar di Rizziconi nel quale gi\u00e0 erano state elevate sanzioni per quasi un milione di euro. Non pago [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":235196,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-236766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/236766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=236766"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/236766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/235196"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=236766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=236766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=236766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}