{"id":236820,"date":"2024-08-02T15:06:10","date_gmt":"2024-08-02T13:06:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=236820"},"modified":"2024-08-02T15:49:12","modified_gmt":"2024-08-02T13:49:12","slug":"incidente-sulla2-tra-gli-svincoli-di-cosenza-sud-e-rende-coinvolte-due-auto-tre-persone-ferite","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/incidente-sulla2-tra-gli-svincoli-di-cosenza-sud-e-rende-coinvolte-due-auto-tre-persone-ferite\/","title":{"rendered":"Incidente sull&#8217;A2 tra gli svincoli di Cosenza Sud e Rende: coinvolte due auto, tre persone ferite"},"content":{"rendered":"<p>COSENZA &#8211; Incidente stradale nel primo pomeriggio di oggi,<strong> lungo l&#8217;Autostrada A2 del Mediterraneo,<\/strong> tra gli svincoli di Cosenza Sud e Cosenza Nord (Rende), in direzione Salerno. Secondo le prime informazioni <strong>l&#8217;incidente ha visto coinvolti una Fiat Freemont e una Volkswagen T-Roc<\/strong>:<strong> 3 le persone rimaste ferite per fortuna in maniera non grave <\/strong>e trasportate all&#8217;Annunziata di Cosenza per gli accertamenti del caso.<\/p>\n<p>L&#8217;incidente sarebbe avvenuto poco prima della <strong>galleria &#8220;Serra Spiga&#8221;<\/strong>, <strong>subito dopo lo l&#8217;immissione verso Nord in A2<\/strong> dalla rampa di accesso di Cosenza Sud. Sul posto, oltre ai sanitari del 118, personale dell&#8217;Anas, i vigili del Fuoco, che si sono occupati della messa in sicurezza del tratto e delle vetture e la polizia Stradale di Acri per tutti gli adempimenti di competenza.\u00a0Segnalati al momento solo lievi rallentamenti, mentre la circolazione stradale \u00e8 stata ripristinata.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Incidente stradale nel primo pomeriggio di oggi, lungo l&#8217;Autostrada A2 del Mediterraneo, tra gli svincoli di Cosenza Sud e Cosenza Nord (Rende), in direzione Salerno. Secondo le prime informazioni l&#8217;incidente ha visto coinvolti una Fiat Freemont e una Volkswagen T-Roc: 3 le persone rimaste ferite per fortuna in maniera non grave e trasportate [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":236824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-236820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/236820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=236820"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/236820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/236824"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=236820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=236820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=236820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}