{"id":237147,"date":"2024-08-07T16:00:00","date_gmt":"2024-08-07T14:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=237147"},"modified":"2024-08-07T16:03:06","modified_gmt":"2024-08-07T14:03:06","slug":"spiaggia-a-libera-abusivamente-occupata-nel-cosentino-restituiti-800-mq-di-suolo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/spiaggia-a-libera-abusivamente-occupata-nel-cosentino-restituiti-800-mq-di-suolo\/","title":{"rendered":"Spiaggia libera abusivamente occupata nel Cosentino: restituiti 800 mq di suolo"},"content":{"rendered":"<p>ALBIDONA (CS) &#8211; I militari della Guardia costiera di Trebisacce e di Montegiordano, sotto il coordinamento operativo della Capitaneria di porto di Corigliano calabro, all\u2019alba di domenica scorsa, 4 agosto, hanno riscontrato l\u2019attivit\u00e0 illecita da parte del titolare di una di una struttura ricettiva sita in localit\u00e0 Torre di Albidona del Comune di Albidona (CS), il quale, privo di qualsiasi titolo di concessione, <strong>aveva abusivamente occupato con attrezzature balneari un tratto di spiaggia libera asservendolo indebitamente all\u2019utilizzo dei propri clienti.<\/strong><\/p>\n<p>I militari dell\u2019Ufficio locale marittimo di Trebisacce e della Delegazione di spiaggia di Montegiordano, dopo aver accertato l\u2019illecito<strong> e posto sotto sequestro decine di ombrelloni con le relative basi e di lettini, hanno provveduto a far sgomberare il tratto di spiaggia interessato dall\u2019abuso in questione, dell\u2019estensione di circa 800 metri quadrati, deferendo all\u2019Autorit\u00e0 giudiziaria il responsabile della violazione.<\/strong> L\u2019azione dei militari scaturisce da un\u2019attenta attivit\u00e0 di controllo sul territorio e da verifiche amministrative, nonch\u00e9 da acquisizione di dati e notizie anche sul web, tramite il monitoraggio delle maggiori piattaforme per la gestione e la prenotazione di servizi turistici, tramite<strong> alcune delle quali la citata struttura ricettiva metteva a disposizione dei propri avventori una \u201cspiaggia privata\u201d,<\/strong> che tale in realt\u00e0 non era, trattandosi di una spiaggia libera illecitamente occupata.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ALBIDONA (CS) &#8211; I militari della Guardia costiera di Trebisacce e di Montegiordano, sotto il coordinamento operativo della Capitaneria di porto di Corigliano calabro, all\u2019alba di domenica scorsa, 4 agosto, hanno riscontrato l\u2019attivit\u00e0 illecita da parte del titolare di una di una struttura ricettiva sita in localit\u00e0 Torre di Albidona del Comune di Albidona (CS), [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":207945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-237147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=237147"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237147\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/207945"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=237147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=237147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=237147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}