{"id":237309,"date":"2024-08-10T09:22:22","date_gmt":"2024-08-10T07:22:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=237309"},"modified":"2024-08-10T09:22:22","modified_gmt":"2024-08-10T07:22:22","slug":"resta-chiuso-in-un-parcheggio-dellunical-sfonda-la-sbarra-per-uscire-denunciato-56enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/resta-chiuso-in-un-parcheggio-dellunical-sfonda-la-sbarra-per-uscire-denunciato-56enne\/","title":{"rendered":"Resta chiuso in un parcheggio dell&#8217;Unical, sfonda la sbarra per uscire: denunciato 56enne"},"content":{"rendered":"<div class=\"M-T-15 content-art\">\n<p>RENDE &#8211; I carabinieri della Tenenza di Rosarno, dopo accertamenti ed in collaborazione con la stazione carabinieri di Rende, <strong>hanno deferito in stato di libert\u00e0 un rosarnese di 56 anni.\u00a0 <\/strong>L\u2019uomo, alla met\u00e0 del mese scorso, si era recato a Rende, presso la sede dell\u2019Universit\u00e0 della Calabria, per assistere alla laurea della nipote. Prima dell\u2019evento, la macchina, una fiat 500 X, era stata parcheggiata in degli stalli interni alla struttura,<strong>\u00a0probabilmente riservati ai dipendenti con diritto di accesso.<\/strong><\/p>\n<div id=\"out_in\">\n<div class=\"ob-smartfeed-wrapper feedIdx-0\">\n<div id=\"outbrain_widget_0\" class=\"OUTBRAIN banner\" data-src=\"https:\/\/www.lacnews24.it\/cronaca\/resta-chiuso-nel-parcheggio-e-distrugge-la-sbarra_194429\/\" data-widget-id=\"AR_1\" data-ob-mark=\"true\" data-browser=\"chrome\" data-os=\"win32\" data-dynload=\"\" data-idx=\"0\">\n<div class=\"ob-widget ob-feed-layout AR_1\">\n<div class=\"ob-widget-header\">Ed infatti, dopo lo svolgimento della seduta di laurea della nipote, nel tornare alla macchina, l\u2019uomo si era visto chiuso dentro nel parcheggio, senza possibilit\u00e0 di uscire con il proprio veicolo. Dopo aver inizialmente provato ad aprire manualmente la sbarra, non tentando nemmeno di avvertire personale dell\u2019universit\u00e0, l\u2019uomo ha pensato bene di forzarne l\u2019apertura verso l\u2019alto, <strong>riuscendovi ma venendo per\u00f2 immortalato dalle telecamere di sicurezza.<\/strong><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Il rosarnese, dopo la denuncia ai carabinieri, \u00e8 stato\u00a0<strong>identificato e deferito in stato di libert\u00e0 per danneggiamento della sbarra.<\/strong>\u00a0Ad ogni modo, il procedimento penale \u00e8 attualmente pendente in fase di indagini e l\u2019effettiva responsabilit\u00e0 della persona deferita, sar\u00e0 vagliata nel corso del successivo processo.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; I carabinieri della Tenenza di Rosarno, dopo accertamenti ed in collaborazione con la stazione carabinieri di Rende, hanno deferito in stato di libert\u00e0 un rosarnese di 56 anni.\u00a0 L\u2019uomo, alla met\u00e0 del mese scorso, si era recato a Rende, presso la sede dell\u2019Universit\u00e0 della Calabria, per assistere alla laurea della nipote. Prima dell\u2019evento, [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":226153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-237309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=237309"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/226153"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=237309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=237309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=237309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}