{"id":23736,"date":"2013-06-24T12:15:50","date_gmt":"2013-06-24T10:15:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23736"},"modified":"2023-01-17T13:21:19","modified_gmt":"2023-01-17T12:21:19","slug":"9468-arrestato-per-ricettazione-e-detenzione-di-marijuana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9468-arrestato-per-ricettazione-e-detenzione-di-marijuana\/","title":{"rendered":"Arrestato per ricettazione e detenzione di marijuana"},"content":{"rendered":"<p>CROTONE \u2013 Giacinto Mancuso, 32enne, gia\u2019 noto alle forze dell\u2019ordine, e\u2019 stato arrestato dai Carabinieri di Isola Capo Rizzuto per ricettazione e detenzione ai fini di spaccio di marijuana.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Una perquisizione e\u2019 stata effettuata nella frazione di Le Cannella, in un edificio abitato da parenti dell\u2019uomo, e un\u2019altra nel suo appartamento dove e\u2019 stato rinvenuto un involucro, nascosto in un armadio della mansarda, che conteneva 36 grammi di marijuana, oltre ad una bilancia di precisione digitale. Inoltre, nella minuziosa perquisizione domiciliare, i Carabinieri hanno scoperto un intero impianto di videosorveglianza (comprensivo di DVR &#8211; Hard Disk), smontato e nascosto in un sacco, risultato rubato (per cui sono in corso accertamenti volti all&#8217;identificazione del proprietario), ma anche scatoloni pieni di sigarette, sigari, confezioni di tabacco, filtri, cartine ed accendini per un valore di oltre 1.500 euro, bottino di due diversi furti effettuati a scapito di un tabacchino di Isola Capo Rizzuto tra la fine di maggio e l&#8217;inizio di giugno del 2013. Il nome del tabacchino svaligiato era riportato ancora su uno degli scatoloni rinvenuti. Mancuso e\u2019 ora in regime di domiciliari, ma i Carabinieri stanno valutando altri elementi volti a scoprire altri furti commessi nella zona negli ultimi mesi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE \u2013 Giacinto Mancuso, 32enne, gia\u2019 noto alle forze dell\u2019ordine, e\u2019 stato arrestato dai Carabinieri di Isola Capo Rizzuto per ricettazione e detenzione ai fini di spaccio di marijuana.<\/p>\n","protected":false},"author":22,"featured_media":23737,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-23736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23736"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23737"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}