{"id":237452,"date":"2024-08-13T11:32:45","date_gmt":"2024-08-13T09:32:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=237452"},"modified":"2024-08-13T11:36:14","modified_gmt":"2024-08-13T09:36:14","slug":"corigliano-rossano-stasi-per-medico-bisogna-chiamare-lelisoccorso-da-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/corigliano-rossano-stasi-per-medico-bisogna-chiamare-lelisoccorso-da-cosenza\/","title":{"rendered":"Corigliano Rossano, Stasi: \u00abper un medico bisogna chiamare l\u2019elisoccorso da Cosenza\u00bb"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; \u00abL\u2019episodio avvenuto <a href=\"https:\/\/quicosenza.it\/news\/provincia\/corigliano-rossano-malore-in-mare-per-un-74enne-interviene-lelisoccorso\">ieri sul nostro litorale<\/a> rappresenta in pieno, in quale <strong>stato imbarazzante<\/strong> sia stato <strong>ridotto il sistema sanitario territoriale<\/strong>. Per soccorrere un bagnante, a cui facciamo sentiti auguri di pronta guarigione, una volta giunta l\u2019ambulanza del 118 ovviamente sprovvista di medico, <strong>\u00e8 stato necessario chiamare l\u2019elisoccorso che, partito da Cosenza, \u00e8 atterrato nei pressi della spiaggia<\/strong>\u00bb.<\/p>\n<p>Sono le parole del sindaco di Corigliano Rossano, Flavio Stasi in riferimento al caso di un anziano di 74 anni, colto da malore mentre si trovava in acqua a Pirro Malena. I bagnanti presenti hanno prestato i primi soccorsi, in <strong>attesa dei sanitari del 118<\/strong>, arrivati prima con un\u2019ambulanza non medicalizzata. L\u2019uomo \u00e8 stato prima stabilizzato sul posto e poi \u00e8 stato necessario <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/mancano-le-ambulanze-con-medici-in-provincia-di-cosenza-e-interviene-lelisoccorso-quanto-costa\">far <\/a><strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/mancano-le-ambulanze-con-medici-in-provincia-di-cosenza-e-interviene-lelisoccorso-quanto-costa\">arrivare un&#8217;eliambulanza<\/a> dotata di un rianimatore a bordo<\/strong>.<\/p>\n<p>\u00abSi potrebbero fare mille digressioni \u2013 evidenzia il sindaco Stasi \u2013 una peggiore dell\u2019altra, ma credo ormai ci sia poco da discutere o polemizzare, semplicemente <strong>chi ha responsabilit\u00e0 di governo del nostro sistema sanitario dovrebbe semplicemente vergognarsi<\/strong> ed alzarsi le maniche almeno per rimediare ai propri disastri\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; \u00abL\u2019episodio avvenuto ieri sul nostro litorale rappresenta in pieno, in quale stato imbarazzante sia stato ridotto il sistema sanitario territoriale. Per soccorrere un bagnante, a cui facciamo sentiti auguri di pronta guarigione, una volta giunta l\u2019ambulanza del 118 ovviamente sprovvista di medico, \u00e8 stato necessario chiamare l\u2019elisoccorso che, partito da Cosenza, [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":237453,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-237452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=237452"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/237453"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=237452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=237452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=237452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}