{"id":23756,"date":"2013-06-25T06:07:27","date_gmt":"2013-06-25T04:07:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23756"},"modified":"2023-01-17T13:21:19","modified_gmt":"2023-01-17T12:21:19","slug":"9478-dal-nord-a-crotone-in-cerca-di-esami-facili-indagate-20-persone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9478-dal-nord-a-crotone-in-cerca-di-esami-facili-indagate-20-persone\/","title":{"rendered":"Dal Nord a Crotone in cerca di esami &#8220;facili&#8221;, indagate 20 persone"},"content":{"rendered":"<p style=\"text-align: justify;\">CROTONE \u2013 Luogo comune o realta\u2019? Sembra che il Sud sia spesso associato ad una maggiore facilita\u2019 negli esami, siano essi scolastici o abilitanti.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">E\u2019 quello che devono aver pensato 20 aspiranti agenti immobiliari provenienti dal Nord Italia (Lombardia, Emilia-Romagna e Liguria) che <strong>avevano trasferito in maniera fittizia la loro residenza nel comune di Rocca di Neto per poter svolgere l&#8217;esame da mediatore immobiliare alla Camera di Commercio di Crotone<\/strong>. Eppure, i carabinieri del comando provinciale di Crotone sono riusciti a scoprire la truffa: un esposto anonimo, \u201cautoctono\u201d presumiamo, ha allertato le autorita\u2019 lamentando il fatto che i giovani provenienti dal Nord toglievano la possibilita&#8217; di essere esaminati a molti ragazzi del luogo, essendo ogni sessione d&#8217;esame riservata a non piu&#8217; di 30 concorrenti. Sono cosi\u2019 partite le indagini che hanno accertato che i giovani avevano trasferito la residenza a Rocca di Neto tutti nello stesso giorno dell&#8217;estate 2012, dopo aver frequentato sempre a Crotone un corso di formazione professionale per essere avviati alla professione di agente immobiliare. I venti aspiranti agenti immobiliari provenienti dal Nord Italia risultano per di piu\u2019 residenti in immobili inesistenti o inadatti a ospitare persone. Le indagini, coordinate da Francesco Carluccio, sostituto procuratore della Repubblica presso la Procura di Crotone, continuano per verificare eventuali complicita&#8217; da parte di dipendenti del Comune di Rocca di Neto, che avrebbero falsamente attestato la residenza dei giovani, e alla Camera di commercio di Crotone, i cui responsabili cosi&#8217; come sottolineato dai carabinieri, hanno fornito una fattiva collaborazione. In queste ore sono in corso varie acquisizioni di documenti utili ai fini delle indagini, operazioni che riguardano anche gli uffici di una cooperativa di servizi con sede a Crotone che avrebbe organizzato i corsi di formazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE \u2013 Luogo comune o realta\u2019? Sembra che il Sud sia spesso associato ad una maggiore facilita\u2019 negli esami, siano essi scolastici o abilitanti.<\/p>\n","protected":false},"author":22,"featured_media":23757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-23756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23756"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23757"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}