{"id":237798,"date":"2024-08-19T16:30:37","date_gmt":"2024-08-19T14:30:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=237798"},"modified":"2024-08-23T07:17:58","modified_gmt":"2024-08-23T05:17:58","slug":"calici-a-corte-torna-ad-aprigliano-un-weekend-di-vino-buon-cibo-e-tradizione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/calici-a-corte-torna-ad-aprigliano-un-weekend-di-vino-buon-cibo-e-tradizione\/","title":{"rendered":"&#8216;Calici a Corte&#8217; torna ad Aprigliano: un weekend di vino, buon cibo e tradizione"},"content":{"rendered":"<p>APRIGLIANO (CS) &#8211; Il pittoresco borgo di Aprigliano, situato nel cuore della Presila Cosentina, si prepara ad accogliere l&#8217;attesissimo evento &#8220;Calici a Corte&#8221;, giunto alla quarta edizione, in programma per il <strong>23 e 24 agosto nella frazione Corte<\/strong>. Questa manifestazione, sotto la guida del direttore artistico e noto chef Enzo Barbieri, unisce l\u2019eccellenza vinicola calabrese alla bellezza storica del borgo e si \u00e8 ormai consolidata come uno degli appuntamenti pi\u00f9 significativi dell&#8217;estate nella regione.<\/p>\n<p>&#8220;<strong>Divertimento, buona cucina, tanta bella gente e ovviamente i migliori vini della Calabria<\/strong> pronti per essere degustati&#8221;, dichiara il sindaco di Aprigliano Alessandro Porco.<\/p>\n<p>Saranno dieci le cantine vinicole, conosciute per la loro capacit\u00e0 di produrre vini che rispecchiano l&#8217;autenticit\u00e0 e la ricchezza del territorio, che presenteranno le loro migliori etichette. <strong>I visitatori avranno l&#8217;opportunit\u00e0 di degustare prodotti tipici locali e una vasta gamma di vini<\/strong>, dai rossi intensi e strutturati ai bianchi aromatici e freschi, senza dimenticare i rosati e i vini dolci, che riflettono il sole e i profumi della Calabria<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>APRIGLIANO (CS) &#8211; Il pittoresco borgo di Aprigliano, situato nel cuore della Presila Cosentina, si prepara ad accogliere l&#8217;attesissimo evento &#8220;Calici a Corte&#8221;, giunto alla quarta edizione, in programma per il 23 e 24 agosto nella frazione Corte. Questa manifestazione, sotto la guida del direttore artistico e noto chef Enzo Barbieri, unisce l\u2019eccellenza vinicola calabrese [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":237799,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-237798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=237798"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/237799"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=237798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=237798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=237798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}