{"id":237865,"date":"2024-08-20T15:27:30","date_gmt":"2024-08-20T13:27:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=237865"},"modified":"2024-08-20T16:32:12","modified_gmt":"2024-08-20T14:32:12","slug":"maltempo-a-cosenza-crolla-il-controsoffitto-di-rianimazione-allannunziata-video","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/maltempo-a-cosenza-crolla-il-controsoffitto-di-rianimazione-allannunziata-video\/","title":{"rendered":"Maltempo a Cosenza, crolla il controsoffitto di Rianimazione all&#8217;Annunziata &#8211; VIDEO"},"content":{"rendered":"<p>COSENZA &#8211; Il <strong>maltempo<\/strong> di queste ore che si \u00e8 abbattuto su tutta <strong><a href=\"https:\/\/quicosenza.it\/news\/italia\/maltempo-domani-ancora-allerta-gialla-su-tutta-la-calabria-da-mercoledi-torna-il-sole\" target=\"_blank\" rel=\"noopener\">la Calabria<\/a><\/strong>, con piogge consistenti dalle prime ore del mattino anche su Cosenza, hanno provocato <strong>disagi anche all&#8217;ospedale Annunziata<\/strong>. La testimonianza arriva da un video postato dalla pagina Facebook dell&#8217;esponente del Pd nazionale, <strong>Carlo Guccione<\/strong>. &#8220;Adesso il nuovo reparto di rianimazione all\u2019ospedale di Cosenza&#8221;, scrive Guccione a corredo delle immagini che mostrano il<strong> crollo di alcuni pezzi di controsoffitto nel reparto di Rianimazione<\/strong> dell&#8217;ospedale di Cosenza, cos\u00ec come riferito da Guccione. I danni si sono registrati anche all&#8217;entrata pedonale del vecchio pronto soccorso.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=476&amp;href=https%3A%2F%2Fwww.facebook.com%2F100001842986547%2Fvideos%2F906955964589886%2F&amp;show_text=false&amp;width=267&amp;t=0\" width=\"267\" height=\"476\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il maltempo di queste ore che si \u00e8 abbattuto su tutta la Calabria, con piogge consistenti dalle prime ore del mattino anche su Cosenza, hanno provocato disagi anche all&#8217;ospedale Annunziata. La testimonianza arriva da un video postato dalla pagina Facebook dell&#8217;esponente del Pd nazionale, Carlo Guccione. &#8220;Adesso il nuovo reparto di rianimazione all\u2019ospedale [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":237866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19,135],"class_list":["post-237865","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=237865"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/237865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/237866"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=237865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=237865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=237865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}