{"id":23792,"date":"2013-06-25T12:32:55","date_gmt":"2013-06-25T10:32:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23792"},"modified":"2023-01-17T13:21:21","modified_gmt":"2023-01-17T12:21:21","slug":"9497-il-dramma-di-zara-hartshorn-la-ragazza-che-dimostra-60-anni-avendone-solo-16","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9497-il-dramma-di-zara-hartshorn-la-ragazza-che-dimostra-60-anni-avendone-solo-16\/","title":{"rendered":"Il dramma di Zara Hartshorn, la ragazza che dimostra 60 anni avendone solo 16"},"content":{"rendered":"<p>Esistono malattie cos\u00ec rare che a volte somigliano pi\u00f9 a crudeli scherzi del destino che a un malessere come nel caso di <strong>Zara Hartshorn<\/strong> una ragazza del South Yorkshire che fin da piccola convive con una rara malattia genetica, la <span style=\"text-decoration: underline;\"><strong>lipodistrofia<\/strong><\/span>.<\/p>\n<p>  <!--more-->  <\/p>\n<p>A causa di questa malattia dimostra almeno <strong>60 anni<\/strong> ma lei all\u2019anagrafe risulta averne solo <strong>16<\/strong>. Ovviamente \u00e8 stata gi\u00e0 protagonista di numerosi episodi di bullismo, pregiudizi di ogni genere anche se in suo aiuto oggi \u00e8 intervenuta la chirurgia estetica.<br \/>Una situazione drammatica che Zara ha ereditato da sua madre <strong>Tracy<\/strong> e con la quale devono convivere anche i suoi fratelli. <br \/>In pratica questa malattia attacca i grassi del corpo conferendogli quindi un\u2019et\u00e0 assai maggiore di quella che si ha in realt\u00e0.<br \/>Dopo aver sentito parlare della sua condizione, un famoso chirurgo degli <strong>Stati Uniti<\/strong> si \u00e8 offerto di operarla gratuitamente. A poco a poco cos\u00ec le rughe si stanno attenuando. <strong>Zara<\/strong> comincia ad avere una vita normale, ha ripreso fiducia in se stessa e ora si \u00e8 anche <strong>fidanzata<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esistono malattie cos\u00ec rare che a volte somigliano pi\u00f9 a crudeli scherzi del destino che a un malessere come nel caso di Zara Hartshorn una ragazza del South Yorkshire che fin da piccola convive con una rara malattia genetica, la lipodistrofia.<\/p>\n","protected":false},"author":22,"featured_media":23793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,22],"tags":[],"class_list":["post-23792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dal-mondo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23792"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23793"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}