{"id":238042,"date":"2024-08-23T09:15:56","date_gmt":"2024-08-23T07:15:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=238042"},"modified":"2024-08-23T13:12:58","modified_gmt":"2024-08-23T11:12:58","slug":"febbre-west-nile-il-primo-paziente-in-calabria-e-stato-isolato-a-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/febbre-west-nile-il-primo-paziente-in-calabria-e-stato-isolato-a-cosenza\/","title":{"rendered":"Febbre West Nile, il primo paziente in Calabria \u00e8 stato isolato a Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; Cresce l&#8217;attenzione in Italia per la febbre del <strong>West Nile,<\/strong> la malattia provocata dal virus che \u00e8 trasmesso da uccelli selvatici e zanzare. <strong>Il primo caso si \u00e8 registrato anche in Calabria, nel Cosentino,<\/strong> <strong>con il paziente 1, un uomo di 85 anni,<\/strong> isolato a Cosenza il 9 agosto. L&#8217;uomo \u00e8 ricoverato nel reparto di Malattie infettive dell&#8217;ospedale dell&#8217;Annunziata e non sarebbe in pericolo di vita. L&#8217;anziano, secondo quanto si apprende, avrebbe sviluppato forme neuroinvasive con le manifestazioni classiche dell&#8217;epidemia. La <strong>Regione Calabria<\/strong>, in questi giorni, ha approvato un <strong><a href=\"https:\/\/quicosenza.it\/news\/calabria\/il-west-nilecs-arriva-in-calabria-la-regione-monitora-il-virus-e-approva-il-piano-di-sorveglianza\" target=\"_blank\" rel=\"noopener\">piano di sorveglianza <\/a><\/strong>per alzare il livello di attenzione sul territorio. Il monitoraggio del virus \u00e8 iniziato a maggio in Italia e da allora sono stati registrati, complessivamente, 171 casi.<\/p>\n<h3>Rizzo: &#8220;nessun rischio epidemiologico, monitoriamo situazione&#8221;<\/h3>\n<p>&#8220;Al momento non c&#8217;\u00e8 alcun rischio epidemiologico &#8211; ha detto <strong>Martino Rizzo, direttore sanitario dell&#8217;Azienda sanitaria provinciale di Cosenza<\/strong> &#8211; stiamo monitorando la situazione \u00e8 le specie che possono trasmettere il virus sono sotto controllo. Stiamo mettendo in atto tutte le misure previste &#8211; ha aggiunto Rizzo &#8211; per il controllo della proliferazione delle zanzare. Escludo grandi rischi, perch\u00e9 si tratta di un&#8217;area delimitata, localizzata intorno all&#8217;abitazione del paziente, dove ti stanno facendo una serie di attivit\u00e0 di prevenzione. Stiamo lavorando con i Comuni interessati per evitare possibili proliferazione e in questo sono in atto attivit\u00e0 di disinfestazione con squadre organizzate che possono intervenire per ogni emergenza&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Cresce l&#8217;attenzione in Italia per la febbre del West Nile, la malattia provocata dal virus che \u00e8 trasmesso da uccelli selvatici e zanzare. Il primo caso si \u00e8 registrato anche in Calabria, nel Cosentino, con il paziente 1, un uomo di 85 anni, isolato a Cosenza il 9 agosto. L&#8217;uomo \u00e8 ricoverato nel [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":238043,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,1],"tags":[19],"class_list":["post-238042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=238042"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/238043"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=238042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=238042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=238042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}