{"id":23812,"date":"2013-06-26T06:26:58","date_gmt":"2013-06-26T04:26:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23812"},"modified":"2023-01-17T13:21:22","modified_gmt":"2023-01-17T12:21:22","slug":"9508-provano-a-lanciare-la-marijuana-dal-balcone-arrestati-studenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9508-provano-a-lanciare-la-marijuana-dal-balcone-arrestati-studenti\/","title":{"rendered":"Provano a lanciare la marijuana dal balcone, arrestati studenti"},"content":{"rendered":"<p>RENDE &#8211; Bussano i carabinieri: &#8220;butta via tutto&#8221;.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Due studenti incensurati di 23 e 27 anni originari di San Giovannni in Fiore sono stati tratti in arresto stamane dal comando dei carabinieri di Rende. I ragazzi a seguito di una perquisizione domiciliare presso l&#8217;abitazione del 23enne in via Marconi, sarebbero stati trovati in possesso di 175 grammi di marijuana. Alla vista dei militari prima di aprire la porta gli studenti avrebbero tentato invano di disfarsi dello stupefacente. Lanciata &#8216;l&#8217;erba&#8217; dak balcone l&#8217;involucro sarebbe caduto al centro di un giardino di propriet\u00e0 di una famiglia in bella vista rendendo inutile l&#8217;escamotage improvvisati dai giovani per scongiurare l&#8217;arresto. Il pi\u00f9 grande dei due ospite nell&#8217;appartamento pare abbia avocato a s\u00e8 la responsabilit\u00e0 del tentativo di occultamento dello stupefacente. Nel corso della perquisizione i militari avrebbero inoltre trovato in casa uno spinello gi\u00e0 &#8216;rollato&#8217; e materiale per la custodia confezionamento della marijuana. I due sono stati condotti presso la casa circondariale di via Popilia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Bussano i carabinieri: &#8220;butta via tutto&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":23813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-23812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23812"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23813"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}