{"id":238140,"date":"2024-08-26T09:00:27","date_gmt":"2024-08-26T07:00:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=238140"},"modified":"2024-08-26T07:43:34","modified_gmt":"2024-08-26T05:43:34","slug":"provincia-della-sibaritide-per-uva-rafforza-il-territorio-ma-serve-anche-lungimiranza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/provincia-della-sibaritide-per-uva-rafforza-il-territorio-ma-serve-anche-lungimiranza\/","title":{"rendered":"Provincia della Sibaritide, per Uva &#8220;rafforza il territorio ma serve anche lungimiranza&#8221;"},"content":{"rendered":"<p class=\"v1default-style\">CORIGLIANO-ROSSANO (CS) \u2013 &#8220;Come fondatore di uno dei comitati che oltre vent&#8217;anni fa lavor\u00f2 duramente alla <strong>istituzione di una provincia della Sibaritide<\/strong>, sono molto felice del fatto che, finalmente, si \u00e8 ripreso un dibattito vero, dopo anni di silenzio, su questo argomento. Si tratta certamente di un merito dell&#8217;attuale Amministrazione che, con l&#8217;Istituzione di una apposita commissione consiliare, ha posto nuovamente la questione, con coraggio ed anche a costo di farsi qualche nemico&#8221;. Lo scrive in una nota<strong> il consigliere comunale di Corigliano Rossano Antonio Uva.<\/strong><\/p>\n<p class=\"v1default-style\">All&#8217;epoca la <strong>mancata istituzione di una provincia dello ionio e del pollino f<\/strong>u certamente causata dalla <strong>poca lungimiranza,<\/strong> per non dire miopia ed irresponsabilit\u00e0, della classe politica dell&#8217;epoca, che non riusc\u00ec \u2013 nel momento decisivo \u2013 a trovare una sintesi per logiche di campanile. Dopo vent&#8217;anni possiamo dire che quella &#8220;non scelta&#8221; ha fatto male a tutti: ai due grandi centri di Rossano e Corigliano che <strong>hanno perso presidi istituzionali basilari; alle vicine Crosia, Cassano, Cariati, Trebisacce,<\/strong> nei quali sono stati tagliati ulteriori servizi ed investimenti; alla vicina Castrovillari che, a parte il pennacchio del Tribunale, restano ben poche prospettive; a tutte le comunit\u00e0 che ruotano intorno ai grandi centri della Sibaritide.<\/p>\n<p class=\"v1default-style\">Oggi credo che questa realt\u00e0 possa essere capovolta per molte ragioni. C&#8217;\u00e8 sicuramente l&#8217;elemento dirompente ed unico della nascita della citt\u00e0 di Corigliano-Rossano, che ha oggettivamente ridefinito l&#8217;assetto istituzionale della Calabria e che deve essere considerato. Ho inoltre la fiducia che oggi alla guida di tutte le istituzioni, locali e non, ci possa essere una classe dirigente che ha imparato dagli errori del passato e che non si rassegni alle solite inutili divisioni politiche o di campanile:<strong> bisogna cambiare la storia.<\/strong> <strong>La Provincia risolver\u00e0 i nostri problemi? No,<\/strong> si tratta di uno strumento che poi dovr\u00e0 essere usato per quello, ma anche di un doveroso riconoscimento di autonomia amministrativa ad un&#8217;area che presenta, di fatto, tutte le caratteristiche politiche, sociali, economiche e territoriali per esserlo.<\/p>\n<p class=\"v1default-style\">\u00c8 da questo presupposto che bisogna partire, un dato di fatto oggettivo, mentre sotto il profilo giuridico, oltre alla presenza di una citt\u00e0 di 80 mila abitanti, \u00e8 proprio nell&#8217;ambito della giusta rivisitazione della legge Delrio e del ruolo delle provincie che riteniamo necessario inserire il ragionamento sulla istituzione della nuova Provincia ed \u00e8 evidente che \u00e8 necessario il supporto di tutte le figure istituzionali del territorio e della Calabria per condividere questo percorso: sar\u00e0 questo uno degli obiettivi della Commissione Consiliare che ha gi\u00e0 ricevuto il totale appoggio del Primo Cittadino di Corigliano-Rossano.<\/p>\n<p class=\"v1default-style\">L&#8217;istituzione della nuova Provincia, sia chiaro, &#8211; conclude Uva &#8211; non serve solo per attivare presidi istituzionali \u2013 cosa comunque importante in un territorio di centinaia di migliaia di persone che si trovano ad un&#8217;ora da servizi basilari \u2013 ma rappresenta uno strumento per garantire al territorio, quindi all&#8217;intera Calabria, maggiore competitivit\u00e0. Si esca dalla logica che la Provincia della Sibaritide serve solo alla Sibaritide o a Corigliano-Rossano: una logica vecchia che non ha mai aiutato la Calabria. Nel grande come nel piccolo, si cresce insieme e la Sibaritide ha ancora un enorme potenziale da esprimere a favore dell&#8217;intera regione&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO-ROSSANO (CS) \u2013 &#8220;Come fondatore di uno dei comitati che oltre vent&#8217;anni fa lavor\u00f2 duramente alla istituzione di una provincia della Sibaritide, sono molto felice del fatto che, finalmente, si \u00e8 ripreso un dibattito vero, dopo anni di silenzio, su questo argomento. Si tratta certamente di un merito dell&#8217;attuale Amministrazione che, con l&#8217;Istituzione di una [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":238135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-238140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=238140"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238140\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/238135"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=238140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=238140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=238140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}