{"id":238221,"date":"2024-08-27T14:37:11","date_gmt":"2024-08-27T12:37:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=238221"},"modified":"2024-08-27T14:37:11","modified_gmt":"2024-08-27T12:37:11","slug":"rapina-la-ex-moglie-e-la-picchia-ripetutamente-anche-davanti-al-figlio-di-5-anni-arrestato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rapina-la-ex-moglie-e-la-picchia-ripetutamente-anche-davanti-al-figlio-di-5-anni-arrestato\/","title":{"rendered":"Rapina la ex moglie e la picchia ripetutamente anche davanti al figlio di 5 anni: arrestato"},"content":{"rendered":"<p>CIRO&#8217; MARINA &#8211; E&#8217; accusato di <strong>ripetuti maltrattamenti e rapina nei confronti dell&#8217;ex moglie:<\/strong> <strong>un trentatreenne \u00e8 stato arrestato dai carabinieri della Compagnia di Cir\u00f2 Marina<\/strong> in esecuzione di un provvedimento cautelare emesso dal gip su richiesta della Procura di Crotone. Secondo l&#8217;impostazione accusatoria accolta dal gip, <strong>l&#8217;uomo a partire dal 2022, avrebbe aggredito fisicamente e verbalmente l&#8217;ex moglie<\/strong> in diverse e ripetute occasioni tanto da ingenerarle uno stato di soggezione e paura tale da costringerla a rimettere una querela gi\u00e0 presentata due anni fa.<\/p>\n<p>I primi accertamenti, condotti subito dopo la <strong>denuncia della donna<\/strong>, hanno consentito di raccogliere un quadro indiziario importante, da cui \u00e8 emerso che le condotte violente, vessatorie e finalizzate anche al controllo degli spostamenti della vittima, nella cui autovettura, nel 2023, avrebbe installato un <strong>rilevatore Gps occulto,<\/strong> non si sarebbero fermate n\u00e9 quando la vittima, a causa di problematiche fisiche, era stata costretta a muoversi utilizzando delle stampelle, n\u00e9 in presenza del loro figlio minore, di cinque anni.<br \/>\nLe indagini dei militari, inoltre, hanno anche consentito di ricostruire <strong>un episodio di rapina<\/strong>, avvenuto nell&#8217;aprile del 2023, quando il trentatreenne, dopo aver aggredito verbalmente la donna, si era impossessato della sua autovettura per poi colpirla con calci e schiaffi. L&#8217;uomo \u00e8 stato portato in carcere.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CIRO&#8217; MARINA &#8211; E&#8217; accusato di ripetuti maltrattamenti e rapina nei confronti dell&#8217;ex moglie: un trentatreenne \u00e8 stato arrestato dai carabinieri della Compagnia di Cir\u00f2 Marina in esecuzione di un provvedimento cautelare emesso dal gip su richiesta della Procura di Crotone. Secondo l&#8217;impostazione accusatoria accolta dal gip, l&#8217;uomo a partire dal 2022, avrebbe aggredito fisicamente [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":238222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-238221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=238221"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/238222"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=238221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=238221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=238221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}