{"id":238445,"date":"2024-09-01T11:00:46","date_gmt":"2024-09-01T09:00:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=238445"},"modified":"2024-09-01T10:24:49","modified_gmt":"2024-09-01T08:24:49","slug":"cosenza-maglia-nera-per-autobus-euro-0-parco-mezzi-ancora-troppo-datato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-maglia-nera-per-autobus-euro-0-parco-mezzi-ancora-troppo-datato\/","title":{"rendered":"Cosenza maglia nera per autobus Euro 0: parco mezzi ancora troppo datato"},"content":{"rendered":"<p class=\"v1MsoNormal\" style=\"text-align: left;\" align=\"center\">COSENZA \u2013\u00a0<b>Continental<\/b>\u00a0ha realizzato anche quest&#8217;anno l&#8217;<b>Osservatorio sui macro-trend del mercato dei veicoli pesanti per il trasporto di merci e persone<\/b>, giunto alla sua\u00a0<b>quarta edizione.<\/b>\u00a0Lo studio fotografa lo stato del settore nelle province italiane<b>\u00a0<\/b>nel\u00a0<b>2023<\/b>, dopo un 2022 caratterizzato da un rallentamento seguito alla ripresa post Covid-19, e prova a tracciare la direzione verso la quale questo comparto si sta dirigendo attraverso l&#8217;analisi dei dati sulle\u00a0<b>immatricolazioni, i tipi di alimentazione, l&#8217;anzianit\u00e0 e la categoria euro<\/b> del parco circolante.<\/p>\n<h3 class=\"v1MsoNormal\"><b><u>Immatricolazioni: a Cosenza +38,7% di nuovi bus<\/u><\/b><\/h3>\n<p class=\"v1MsoNormal\">Il trasporto merci oltre le 16t nel 2023 in Italia ha registrato 22.999 nuove immatricolazioni, con un aumento del 6,9%<b>\u00a0<\/b>rispetto al 2022. La<b>\u00a0Calabria<\/b>\u00a0va in controtendenza e, nonostante la presenza di alcune grandi flotte,\u00a0<b>chiude in negativo con 415 nuove targhe (-20,7%)<\/b>.\u00a0<b>A Cosenza la decrescita si accentua notevolmente registrando -44,5%<\/b>\u00a0di immatricolazioni (da 236 unit\u00e0 del 2022 a 131 del 2023).<\/p>\n<p class=\"v1MsoNormal\">Il<b>\u00a0<\/b>mercato italiano degli autobus, indipendentemente dalla capienza, registra un +45,8%<b>\u00a0<\/b>con 5.434 immatricolazioni tra trasporto pubblico locale, regionale, nazionale e noleggio da rimessa. In questo contesto la\u00a0<b>Calabria segna una crescita notevole (+111,6%)<\/b>\u00a0al netto di 201 nuove targhe (rispetto alle 95 dell&#8217;anno precedente).\u00a0<b>Cosenza segue il trend positivo e chiude con +38,7%,<\/b>\u00a0pari a 43 nuovi bus (vs 31 del 2022).<\/p>\n<h3 class=\"v1MsoNormal\"><b><u>Alimentazione: a Cosenza cresce l&#8217;ibrido tra i mezzi pesanti<\/u><\/b><\/h3>\n<p class=\"v1MsoNormal\"><a name=\"v1_Hlk138781496\"><\/a><a name=\"v1_Hlk138781427\"><\/a>La situazione italiana per alimentazione del\u00a0<b>parco merci<\/b>\u00a0circolante nel 2023 (relativa agli autocarri di ogni peso totale a terra) rimane quasi invariata rispetto al 2022:\u00a0il gasolio continua ad essere predominante (90,3%) seguito da benzina e metano (a 4,5% e 2,1%). Timidissima crescita per le alimentazioni alternative: i veicoli a GPL segnano un +1,5% contro l&#8217;1,4% del 2022, cos\u00ec come gli elettrici (0,4% contro lo 0,3%); crescita pi\u00f9 sostenuta per gli ibridi (0,5% se con motore termico a gasolio e 0,6% a benzina).<\/p>\n<p class=\"v1MsoNormal\">In\u00a0<b>Calabria<\/b>\u00a0si segnala un\u00a0<b>lieve calo del<\/b>\u00a0<b>gasolio<\/b>, che rimane comunque preponderante e copre il\u00a0<b>94,6%<\/b>\u00a0del parco (-0,2 punti percentuali rispetto al 2022). Il metano rimane stabile allo 0,6%. La\u00a0<b>crescita<\/b>\u00a0interessa il comparto degli\u00a0<b>ibridi<\/b>\u00a0(+0,2 punti percentuali) che, tra benzina e gasolio, si attestano a quota\u00a0<b>0,5%.<\/b><\/p>\n<p class=\"v1MsoNormal\">Stesso andamento a\u00a0<b>Cosenza, con gli ibridi in aumento allo 0,5%,<\/b>\u00a0il metano fermo allo 0,9% e il gasolio in discesa al 94,9%.<\/p>\n<p class=\"v1MsoNormal\">Il parco\u00a0<b>autobus<\/b>\u00a0nazionale (di tutte le dimensioni) vede una lenta transizione verso le alimentazioni alternative, dovuta essenzialmente ai cambiamenti in atto nelle flotte di TPL urbano e interurbano a breve raggio: la maggioranza del circolante rimane a gasolio (91,1%), il metano \u00e8 al 6,1% e le quote di\u00a0<a name=\"v1_Hlk138173403\"><\/a>elettrico e ibrido diesel raggiungono il 2,2%\u00a0(rispettivamente 1,3% e 0,9%).<\/p>\n<p class=\"v1MsoNormal\">In\u00a0<b>Calabria si assiste a una crescita di tutte le alimentazioni alternative<\/b>: l&#8217;elettrico passa da 0,1% a 0,3% e l&#8217;ibrido da 0 a 0,2%. Cala di 0,3 punti percentuali il metano e di 0,1 il gasolio.<\/p>\n<p class=\"v1MsoNormal\">Viceversa a\u00a0<b>Cosenza<\/b>\u00a0il gasolio aumenta di 0,5 punti percentuali arrivando a 96,8%. Il metano scende da 3 a 2,3% e\u00a0<b>l&#8217;ibrido cresce da 0 a 0,3%.<\/b><\/p>\n<h3 class=\"v1MsoNormal\"><b><u>Categoria Euro: Cosenza maglia nera per bus Euro 0<\/u><\/b><\/h3>\n<p class=\"v1MsoNormal\"><a name=\"v1_Hlk138781650\"><\/a>Nel comparto degli autocarri per\u00a0<b>trasporto merci<\/b>\u00a0nel 2023 prevalgono a livello nazionale gli Euro 4, 5 e 6 che, insieme, raggiungono il 55,5% del totale. I dati di Euro 0, 1, 2 e 3 (pari al 44% complessivo) necessiterebbero di analisi approfondite in quanto potrebbero essere viziati da iscrizioni al PRA di veicoli non pi\u00f9 circolanti.<\/p>\n<p class=\"v1MsoNormal\"><b>Maglia nera in Italia, la Calabria ha il parco merci pi\u00f9 inquinante<\/b>: qui gli Euro dallo 0 al 3 coprono il 67,5%.<\/p>\n<p class=\"v1MsoNormal\">In linea con la panoramica regionale,\u00a0<b>Cosenza registra il 66,8% di mezzi inquinanti.\u00a0<\/b>Per contro le classi Euro 5 ed Euro 6 raggiungono l&#8217;8,2% e il 10,1% (rispetto al 7,8% e 9,6% regionale).<\/p>\n<p class=\"v1MsoNormal\">In Italia, la percentuale di\u00a0<b>autobus<\/b>\u00a0Euro 4, 5 e 6 rappresenta il 59,3% del parco. Anche in questo caso la quota degli Euro 0 e 1 potrebbe non riflettere puntualmente i bus realmente in circolazione, mentre i veicoli Euro 2 ed Euro 3 passano al 39,9% sul totale.<\/p>\n<p class=\"v1MsoNormal\"><b>La Calabria registra una netta prevalenza di veicoli inquinanti, il 57,8%.\u00a0<\/b>Tra le classi pi\u00f9 ecologiche gli Euro 5 arrivano al 15% e gli Euro 6 al 18,4%.<\/p>\n<p class=\"v1MsoNormal\"><b>A Cosenza si segnala il picco regionale di Euro 0 (21,1%)<\/b>\u00a0cifra che, se sommata alle classi 1,2 e 3, arriva a sfiorare il 58%.<\/p>\n<h3 class=\"v1MsoNormal\"><b><u>Anzianit\u00e0: a Cosenza il 42% dei bus ha oltre 20 anni<\/u><\/b><\/h3>\n<p class=\"v1MsoNormal\"><a name=\"v1_Hlk138781848\"><\/a>L&#8217;et\u00e0 degli autocarri in circolazione in Italia rispecchia a grandi linee la loro classe ecologica; la percentuale di veicoli con meno di un anno aumenta dal 3,6% al 4,4% ma allo stesso tempo invecchiano quelli seminuovi, con un calo di 0,7 punti percentuali dei veicoli tra uno e cinque anni. I dati dei pi\u00f9 anziani potrebbero essere anche qui viziati dal permanere sui registri di veicoli non pi\u00f9 circolanti, tanto che la fascia oltre i 20 anni risulta la pi\u00f9 diffusa con il 35,3% del circolante.<\/p>\n<p class=\"v1MsoNormal\"><b>In Calabria la fascia pi\u00f9 rappresentata \u00e8 quella di autocarri tra 20 e 30 anni<\/b>, che copre il 26,6% del totale circolante.\u00a0<b>Rispetto alla media nazionale la Calabria presenta un parco decisamente pi\u00f9 datato<\/b>: il 30,6% dei veicoli ha pi\u00f9 di 30 anni (15,8% in Italia) e quelli sotto i 10 anni scendono al 14,3% (35,2% Italia).<\/p>\n<p class=\"v1MsoNormal\"><b>In provincia di Cosenza l&#8217;et\u00e0 media degli autocarri riflette il dato regionale:\u00a0<\/b>il 29,7% supera i 30 anni e il 15,4% ha meno di 10 anni. La fascia pi\u00f9 diffusa rimane quella tra i 20 e i 30 anni che sale al 26,2% (+1,2 punti percentuali rispetto al 2022).<b><\/b><\/p>\n<p class=\"v1MsoNormal\">Gli autobus italiani risentono positivamente dei contributi per le flotte di TPL e generalmente i mezzi pi\u00f9 vecchi registrano dati pi\u00f9 aderenti alla realt\u00e0 rispetto agli autocarri di pari et\u00e0. Aumentano i veicoli con meno di due anni (da 3,7% a 5,5% quelli fino a un anno) e in generale il 38,6% ha meno di dieci anni (contro il 36,2% del 2022).<\/p>\n<p class=\"v1MsoNormal\">Anche in questo caso\u00a0<b>la Calabria mostra veicoli pi\u00f9 datati<\/b>\u00a0rispetto alla media nazionale: i veicoli\u00a0<b>sopra i 20 anni raggiungono quota 40,9%<\/b>\u00a0(vs 27,5% dell&#8217;Italia) e quelli\u00a0<b>sotto i 10 anni il 22,2%.<\/b>\u00a0La fascia pi\u00f9 diffusa \u00e8 quella tra i 15 e i 20 anni (pari al 23,5%).<\/p>\n<p class=\"v1MsoNormal\"><b>A Cosenza\u00a0<\/b>il 19,7% del circolante ha meno di 10 anni e gli\u00a0<b>autobus datati salgono a 42,1%.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013\u00a0Continental\u00a0ha realizzato anche quest&#8217;anno l&#8217;Osservatorio sui macro-trend del mercato dei veicoli pesanti per il trasporto di merci e persone, giunto alla sua\u00a0quarta edizione.\u00a0Lo studio fotografa lo stato del settore nelle province italiane\u00a0nel\u00a02023, dopo un 2022 caratterizzato da un rallentamento seguito alla ripresa post Covid-19, e prova a tracciare la direzione verso la quale questo [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":229905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-238445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=238445"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/229905"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=238445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=238445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=238445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}