{"id":238632,"date":"2024-09-01T23:33:24","date_gmt":"2024-09-01T21:33:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=238632"},"modified":"2024-09-01T23:33:24","modified_gmt":"2024-09-01T21:33:24","slug":"alvini-il-pareggio-e-un-risultato-giusto-ma-potevamo-portarla-a-casa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/alvini-il-pareggio-e-un-risultato-giusto-ma-potevamo-portarla-a-casa\/","title":{"rendered":"Alvini &#8220;il pareggio \u00e8 un risultato giusto, ma potevamo portarla a casa&#8221;"},"content":{"rendered":"<p>PALERMO &#8211; <strong>C&#8217;\u00e8 soddisfazione ma anche un pizzico di rammarico<\/strong> nelle parole del tecnico del Cosenza Alvini al termine del match contro il Palermo finito <a href=\"https:\/\/quicosenza.it\/news\/sport\/super-goal-di-fumagalli-e-zampata-di-di-mariano-il-cosenza-strappa-un-ottimo-pari-a-palermo-1-1\" target=\"_blank\" rel=\"noopener\">1 a 1<\/a> con <strong>i rossoblu raggiunti in zona cesarini dalla zampata di Di Mariano<\/strong> che ha riequilibrato l&#8217;iniziale vantaggio rossoblu siglato da Fumagalli. &#8220;Il risultato \u00e8 giusto &#8211; ha esordito Alvini &#8211; <strong>ma lasciamo due punti perch\u00e9 potevamo portarla a casa.<\/strong> Se prendiamo gol a difesa schierata non va bene perch\u00e8 poi rischi anche di perderla. <strong>Comunque la prestazione, l\u2019atteggiamento e quanto messo in campo contro una grande squadra \u00e8 frutto di sacrificio e di voglia<\/strong>. E quindi da questo punto di vista \u00e8 positivo&#8221;.<\/p>\n<p>\u201cForse a un certo punto della partita<strong> potevamo gestire meglio le situazioni e con il possesso potevamo fargli male<\/strong>. Alla fine con due punte in campo la squadra \u00e8 tornata anche a fare la partita ma sono saltati alcuni equilibri. <strong>Dispiace, fermo restando che il pareggio \u00e8 meritato da parte del Palermo, per\u00f2 a volte si possono vincere partite pi\u00f9 sporche e questo fa parte del calcio<\/strong>. Abbiamo avuto problemi nella gestione dei cambi, per\u00f2 alla fine ho voluto gestirla in un determinato modo. Nessun rammarico, ho fatto le sostituzioni che ritenevo opportuno fare. <strong>Chi \u00e8 entrato ha dato un ottimo contributo<\/strong>. Alla squadra non devo dire nulla, solo fargli capire che<strong> in queste 4 partite avremmo potuto raccogliere qualcosa di pi\u00f9<\/strong>. Punti che possono fare la differenza alla fine del campionato&#8221;.<\/p>\n<p><strong>Il Palermo? Abbiamo sofferto il loro palleggio sopratutto gli esterni<\/strong>, abbiamo cambiato due volte la pressione individuale perch\u00e9 ci allungavano ma abbiamo retto per\u00f2. <strong>Noi siamo stati bravi in mezzo a lavorare ai fianchi di Gomes per poi andare dentro<\/strong>. \u00c8 stata una buona partite con tante letture interne al match da parte di entrambe le squadre&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PALERMO &#8211; C&#8217;\u00e8 soddisfazione ma anche un pizzico di rammarico nelle parole del tecnico del Cosenza Alvini al termine del match contro il Palermo finito 1 a 1 con i rossoblu raggiunti in zona cesarini dalla zampata di Di Mariano che ha riequilibrato l&#8217;iniziale vantaggio rossoblu siglato da Fumagalli. &#8220;Il risultato \u00e8 giusto &#8211; ha [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":237746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-238632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=238632"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/237746"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=238632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=238632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=238632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}