{"id":238647,"date":"2024-09-02T07:30:48","date_gmt":"2024-09-02T05:30:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=238647"},"modified":"2024-09-02T11:14:02","modified_gmt":"2024-09-02T09:14:02","slug":"la-dea-bendata-bacia-montalto-e-santa-maria-del-cedro-con-due-piccole-vincite","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/la-dea-bendata-bacia-montalto-e-santa-maria-del-cedro-con-due-piccole-vincite\/","title":{"rendered":"La dea bendata bacia Montalto e Santa Maria del Cedro con due piccole vincite"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Reggio Calabria<\/strong> baciata dalla fortuna grazie al 10eLotto. Nel concorso di venerd\u00ec 30 agosto, come riporta Agipronews, <strong>vinti 20mila euro<\/strong> in seguito a un \u201c9\u201d in un&#8217;estrazione frequente. Da segnalare anche<strong> una vincita da 4mila euro a Santa Maria del Cedro, in provincia di Cosenza, una da 3.500 euro a Montalto Uffugo (CS)<\/strong> e una da 3.500 euro a Crotone. L&#8217;ultimo concorso del 10eLotto ha distribuito 10,3 milioni di euro, per un totale di oltre 2,5 miliardi da inizio anno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Reggio Calabria baciata dalla fortuna grazie al 10eLotto. Nel concorso di venerd\u00ec 30 agosto, come riporta Agipronews, vinti 20mila euro in seguito a un \u201c9\u201d in un&#8217;estrazione frequente. Da segnalare anche una vincita da 4mila euro a Santa Maria del Cedro, in provincia di Cosenza, una da 3.500 euro a Montalto Uffugo (CS) [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":222075,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-238647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=238647"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222075"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=238647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=238647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=238647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}