{"id":238664,"date":"2024-09-02T15:30:22","date_gmt":"2024-09-02T13:30:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=238664"},"modified":"2024-09-02T14:24:14","modified_gmt":"2024-09-02T12:24:14","slug":"salvini-promette-nuovo-codice-della-strada-entro-settembre-autovelox-e-zona-30-solo-dove-servono","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/salvini-promette-nuovo-codice-della-strada-entro-settembre-autovelox-e-zona-30-solo-dove-servono\/","title":{"rendered":"Salvini promette: nuovo codice della strada entro settembre. Autovelox e zona 30 &#8220;solo dove servono&#8221;"},"content":{"rendered":"<p>MILANO &#8211; &#8220;Da un anno lavoriamo a un<strong> nuovo codice della strada<\/strong>, abbiamo coinvolto i Comuni, le Regioni, i produttori di auto, i ciclisti, i familiari delle vittime della strada. Conto che il Parlamento, dopo un ampio dibattito andato avanti quasi 12 mesi, entro settembre approvi in via definitiva il testo che dovr\u00e0 essere applicato&#8221;. Lo ha detto il ministro delle Infrastrutture e Trasporti <strong>Matteo Salvini<\/strong> intervenendo alla presentazione, a Milano, della campagna Onu sulla sicurezza stradale con il sindaco Giuseppe Sala e Jean Todt.<br \/>\nSalvini ha poi citato i dati che sono &#8220;in leggero miglioramento con un -4% di morti, ma siamo a 3039 morti nel 2023, un Comune della provincia di Milano che scompare ogni anno, si tratta di 1322 vittime per le auto, seguite dalle due ruote&#8221;. Mentre sono aumentati di 400 gli incidenti sui monopattini, &#8220;un altro mezzo di locomozione per cui ci sar\u00e0 obbligo di casco, assicurazione perch\u00e9 vanno anche a 40-50 all&#8217;ora&#8221;.<\/p>\n<h3>Salvini, serve buonsenso su Zone 30 e autovelox<\/h3>\n<div id=\"txt_cont\">\u00a0&#8220;Con Anci abbiamo due temi caldi, quello del<strong> limite di 30 all&#8217;ora e quello degli autovelox, conto che li stiamo portando ad punto di caduta di buon senso<\/strong>&#8220;. Lo ha detto il ministro delle Infrastrutture e Trasporti Matteo Salvini intervenendo alla presentazione, a Milano, della campagna Onu sulla sicurezza stradale con il sindaco Giuseppe Sala e Jean Todt. Le zone 30 &#8220;dove si ravvisa un pericolo assolutamente s\u00ec o in zone limitate della citt\u00e1 &#8211; ha aggiunto -, ma arrivare a superfici di 70, 80%, alte della citt\u00e0 a 30 all&#8217;ora pu\u00f2 comportare un disagio all&#8217;operativit\u00e0 della citt\u00e0&#8221;. <strong>Come con gli autovelox, &#8220;dove si ravvisa la necessit\u00e0 \u00e9 doveroso installarli<\/strong> ma penso non al centro di Milano, ma alle grandi arterie &#8211; ha continuato il ministro -, perch\u00e9 si eviti di trasformarlo in uno strumento che ha altri obiettivi&#8221;, come quello di fare cassa. &#8220;Ci sono zone dove il 30 all&#8217;ora e gli autovelox sono necessari e altre zone dove l&#8217;obiettivo \u00e8 altro&#8221;, ha concluso<\/div>\n<div><\/div>\n<h3><strong>&#8220;A lavoro per superare le sentenze su autovelox&#8221;<\/strong><\/h3>\n<div>In merito al tema della<strong> doppia omologazione degli autovelox<\/strong>, &#8220;proprio oggi dovrei firmare una lettera per invitare al tavolo sia l&#8217;Anci, che i ministeri competenti per <strong>superare le sentenze c<\/strong>he hanno messo in difficolt\u00e0 non solo tanti comuni ma lo stesso ministero&#8221;. Lo ha detto il ministro delle Infrastrutture e Trasporti Matteo Salvini intervenendo alla presentazione, a Milano, della campagna Onu sulla sicurezza stradale con il sindaco Giuseppe Sala e Jean Todt. &#8220;L&#8217;obiettivo \u00e8 di arrivare a un testo condiviso con gli altri ministeri e gli enti locali&#8221;, ha concluso.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MILANO &#8211; &#8220;Da un anno lavoriamo a un nuovo codice della strada, abbiamo coinvolto i Comuni, le Regioni, i produttori di auto, i ciclisti, i familiari delle vittime della strada. Conto che il Parlamento, dopo un ampio dibattito andato avanti quasi 12 mesi, entro settembre approvi in via definitiva il testo che dovr\u00e0 essere applicato&#8221;. [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":238670,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-238664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=238664"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/238664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/238670"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=238664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=238664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=238664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}