{"id":23904,"date":"2013-06-28T08:07:32","date_gmt":"2013-06-28T06:07:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23904"},"modified":"2023-01-17T13:21:28","modified_gmt":"2023-01-17T12:21:28","slug":"9554-maltrattamenti-al-centro-minori-dipendente-denuncia-ma-viene-licenziato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9554-maltrattamenti-al-centro-minori-dipendente-denuncia-ma-viene-licenziato\/","title":{"rendered":"Maltrattamenti al centro minori: dipendente denuncia, ma viene licenziato"},"content":{"rendered":"<p style=\"text-align: justify;\">COSENZA \u2013 Abusi e truffa nella casa di accoglienza di Celico.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">E\u2019 stato notificato solo qualche giorno fa il reintegro di Giancarlo, educatore della Cooperativa Sociale di Servizi e Assistenza Onlus di Celico che gestisce due gruppi appartamento per ragazzi a rischio segnalati dal Tribunale dei Minori. Proprio all\u2019interno delle strutture dedicate ai minorenni in particolari condizioni di disagio sottoposti a provvedimenti disposti dalle autorit\u00e0 giudiziarie pare si siano consumati due episodi di estrema gravit\u00e0: il pestaggio di un ragazzino da parte di un operatore e l\u2019appropriazione indebita di denaro da destinare al pagamento dei dipendenti. Due episodi puntualmente denunciati dall\u2019educatore che da venticinque anni lavorava per la cooperativa incassando un plateale licenziamento in tronco dalla cooperativa. \u201cNel 2009 \u2013 racconta Giancarlo \u2013 ho fatto presente che nella struttura c\u2019era chi si appropriava indebitamente del denaro che inviava la Regione. Ho fatto nome e cognome. Ho chiesto i documenti, in qualit\u00e0 di socio, per dimostrare che la gestione economica era poco chiara. Tutti sapevano, ma mi hanno reso la vita impossibile. Mi \u00e8 venuto anche un infarto. Sono stato costretto ad allontanarmi temporaneamente dal posto di lavoro. Quando sono rientrato dopo tre giorni mi hanno licenziato per \u2018incompatibilit\u00e0 di carattere\u2019. Il giudice per\u00f2 nell\u2019arbitrato mi ha dato ragione. C\u2019erano le carte che parlavano: la cuoca era andata in pensione, nessuno lo aveva comunicato alla Regione che continuava a pagare il suo stipendio che finiva direttamente nelle tasche del soggetto da me indicato\u201d. Giancarlo ricomincia a lavorare nel gruppo appartamento continuando le attivit\u00e0 con i ragazzi. Sino al giorno in cui un episodio raccapricciante lo riporta a scontrarsi con la dirigenza. \u201cL\u2019estate scorsa un pomeriggio un mio collega che era di turno \u2013 ricorda l\u2019educatore \u2013 aveva portato con s\u00e9 al lavoro suo figlio dodicenne per farlo giocare con i ragazzi. Un utente del gruppo appartamento, un ragazzo quindicenne buono e solitamente educato, scherza con il ragazzino scimmiottandolo alle spalle come di consueto accade tra gli adolescenti. La reazione del padre \u00e8 stata estrema: lo ha massacrato di botte continuandolo a picchiare anche quando era a terra sanguinante ed ingiuriandolo con insulti che non oso ripetere. La cosa vergognosa \u00e8 stata che nonostante il giorno dopo il quindicenne fosse pieno di lividi e traumatizzato \u00e8 stato costretto finanche a chiedere scusa. Una vera e propria ingiustizia di fronte la quale non potevo chiudere gli occhi. Ho denunciato tutto ai servizi sociali della Regione. E sono stato nuovamente licenziato. Anche in questo caso ho vinto l\u2019arbitrato. Ieri \u00e8 arrivato il reintegro. Aspetto che mi chiamino per tornare al lavoro\u201d. Nel frattempo anche la moglie di Giancarlo viene licenziata dalla cooperativa. E la famiglia dell\u2019operatore, con un figlio minore, resta senza reddito. Giancarlo ha vinto parzialmente la sua causa, il posto di lavoro c\u2019\u00e8, ma i presunti \u2018ladri\u2019 e \u2018violenti\u2019 continueranno ad \u2018educare\u2019 i minori a rischio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Abusi e truffa nella casa di accoglienza di Celico.<\/p>\n","protected":false},"author":22,"featured_media":23905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-23904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23904"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23905"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}