{"id":239610,"date":"2024-09-15T17:52:04","date_gmt":"2024-09-15T15:52:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=239610"},"modified":"2024-09-15T17:52:04","modified_gmt":"2024-09-15T15:52:04","slug":"cosenza-mister-alvini-vittoria-meritata-contento-per-la-squadra-e-i-tifosi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-mister-alvini-vittoria-meritata-contento-per-la-squadra-e-i-tifosi\/","title":{"rendered":"Cosenza, mister Alvini \u00abvittoria meritata, contento per la squadra e i tifosi\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Il <strong>Cosenza<\/strong> rompe il tab\u00fa <strong>Sampdoria<\/strong> portando a casa un successo bello e meritato, figlio di una <a href=\"https:\/\/quicosenza.it\/news\/sport\/il-cosenza-spezza-il-tabu-sampdoria-dorazio-e-strizzolo-regalano-3-punti-doro-ai-rossoblu\">grande prestazione dei rossoblu<\/a> soprattutto nel primo tempo, quando in campo si \u00e9 vista una sola squadra. A fine gara tutta la <strong>soddisfazione<\/strong> del <strong>tecnico Alvini:<\/strong> \u00abla vittoria merito della squadra con un promo tempo di livello dove forse meritavamo di chiuderlo diversamente\u00bb.<\/p>\n<p>\u00ab<strong>Nella ripresa abbiamo sofferto<\/strong> contro una grande squadra &#8211; prosegue il tecnico &#8211; che aveva gamba e che ha poi messo in campo giocatori di grande forza. Ci sono tanti spunti per migliorare, come il goal del pareggio dove ci siamo fatti infilare. <strong>Sono contento per la squadra e per i tifosi; una vittoria meritata<\/strong>. Ad un certo punto la qualit\u00e0 della Samp \u00e9 uscita fuori e l\u00ec dovevamo essere pi\u00f9 bravi anche nella gestione del pallone, cosa che abbiamo fatto bene nell&#8217;ultima parte di gara. Ora sabato prossimo arriva un&#8217;altra grande squadra come il Sassuolo e dobbiamo farci trovare pronti\u00bb.<\/p>\n<div dir=\"auto\">\u00abDobbiamo mantenere un grande equilibrio e dobbiamo anvora migliorare tanto. Non esaltiamoci troppo per la vittoria contro la <strong>Cremonese<\/strong> e la <strong>Sampdoria<\/strong> e <strong>continuiamo a lavorare<\/strong>. Certo che i successi fanno piacere e queste prestazioni ci aiutano a crescere verso il nostro traguardo che \u00e9 la salvezza. <strong>Sabato mi piacerebbe vedere un Marulla pieno perch\u00e9 i ragazzi lo meritano&#8221;.<\/strong><\/div>\n<div dir=\"auto\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il Cosenza rompe il tab\u00fa Sampdoria portando a casa un successo bello e meritato, figlio di una grande prestazione dei rossoblu soprattutto nel primo tempo, quando in campo si \u00e9 vista una sola squadra. A fine gara tutta la soddisfazione del tecnico Alvini: \u00abla vittoria merito della squadra con un promo tempo di [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":239606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-239610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=239610"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/239606"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=239610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=239610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=239610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}