{"id":239619,"date":"2024-09-16T09:16:07","date_gmt":"2024-09-16T07:16:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=239619"},"modified":"2024-09-16T09:16:07","modified_gmt":"2024-09-16T07:16:07","slug":"province-meno-sicure-milano-roma-e-firenze-le-piu-pericolose-cosenza-e-al-95-posto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/province-meno-sicure-milano-roma-e-firenze-le-piu-pericolose-cosenza-e-al-95-posto\/","title":{"rendered":"Province meno &#8216;sicure&#8217;: Milano, Roma e Firenze le pi\u00f9 pericolose. Cosenza \u00e8 al 95\u00b0 posto"},"content":{"rendered":"<p>ROMA &#8211; Le grandi metropoli turistiche <strong>Milano, Roma e Firenze<\/strong> si confermano anche quest&#8217;anno le <strong>peggiori<\/strong> <a href=\"https:\/\/lab24.ilsole24ore.com\/indice-della-criminalita\/classifica\/\" rel=\"noopener\"><strong>nell\u2019Indice della Criminalit\u00e0 2024 del Sole 24 Ore<\/strong><\/a>, la graduatoria su <strong>base provinciale<\/strong> che ogni anno permette di scoprire quali sono le province meno sicure. <strong>Anche la top 10 \u00e8 popolata da grandi citt\u00e0 e mete turistiche<\/strong>. A livello nazionale le denunce sono in aumento per la prima volta dal 2013, con una crescita del 3,8% rispetto al 2022, con particolare aumento dei reati violenti: omicidi, percosse, lesioni e rapine.<\/p>\n<h4><strong>Milano maglia nera<\/strong><\/h4>\n<p>Milano si conferma la <strong>citt\u00e0 con il maggior numero di reati denunciati nel 2023<\/strong>, con oltre 7mila segnalazioni ogni 100mila abitanti nel 2023. Nel capoluogo lombardo, da anni in cima a questa classifica, le denunce sono in crescita del 4,9% rispetto al periodo pre-pandemia, con picchi di furti e rapine. \u00c8 terza per violenze sessuali e quinta per reati connessi agli stupefacenti. <strong>Fabio Roia<\/strong>, presidente del Tribunale di Milano, commenta al Sole 24 Ore: \u00abApparentemente c\u2019\u00e8 questo triste primato, ma non mi sento il presidente del tribunale di Gotham city. C\u2019\u00e8 un forte problema di risorse: in polizia e carabinieri risultano carenze di organico importanti. Le scarse denunce in altre aree del Paese possono significare che il controllo del territorio sia appaltato a realt\u00e0 alternative allo Stato\u00bb.<\/p>\n<h4><strong>Roma in salita<\/strong><\/h4>\n<p>La capitale registra un incremento delle denunce del 16,7% rispetto al 2019 e del +11% rispetto al 2022, con furti e reati predatori a fare da traino, ma anche reati connessi agli stupefacenti. Rispetto alla crescita di questi numeri l\u2019ex procuratore di Milano, <strong>Francesco Greco<\/strong>, ora delegato alla sicurezza per il Comune di Roma, sottolinea al Sole 24 Ore: \u00abAumentano i reati ma anche la fiducia delle persone, pi\u00f9 propense a denunciare. Dalle statistiche non emerge una vera emergenza sul lungo periodo ma il numero di reati violenti \u00e8 alto e i cittadini si sentono insicuri. Stiamo investendo in forme di videosorveglianza che utilizzeranno l\u2019Ai: l\u2019algoritmo ci invier\u00e0 segnalazioni a cui potremo rispondere in modo tempestivo\u00bb.<\/p>\n<h4><strong>Firenze e l&#8217;impennata di rapine<\/strong><\/h4>\n<p><strong>Firenze torna sul podio della criminalit\u00e0<\/strong>, trainata da un aumento delle rapine in strada, cresciute del 56% rispetto al 2022. La sindaca<strong> Sara Furnaro<\/strong> collega questo aumento all\u2019abuso di nuove droghe, come spiega al Sole 24 Ore: \u00abI problemi sono in parte collegati all\u2019aumento dell\u2019uso di alcuni stupefacenti come il crack\u00bb. La situazione impone misure urgenti, eppure il fenomeno sembra legato anche al flusso turistico: le grandi citt\u00e0, meta di milioni di visitatori ogni anno, vedono crescere i reati predatori e violenti.<\/p>\n<h4><strong>L&#8217;impatto delle citt\u00e0 metropolitane<\/strong><\/h4>\n<p>Un&#8217;altra novit\u00e0 dell\u2019edizione 2024 \u00e8 l&#8217;analisi dell&#8217;incidenza delle citt\u00e0 metropolitane sul totale delle denunce. Il 30% dei reati in Italia nel 2023 \u00e8 stato segnalato proprio nei 14 capoluoghi principali, con Milano e Roma che da sole rappresentano il 15% del totale. La top 10 della classifica \u00e8 popolata da grandi citt\u00e0 e mete turistiche:<strong> Firenze (3\u00aa), Rimini (4\u00aa), Torino (5\u00aa), Bologna (6\u00aa), Prato (7\u00aa), Imperia (8\u00aa) e Livorno (10\u00aa). Napoli (12\u00aa),<\/strong> invece, cede il posto a <strong>Venezia (9\u00aa)<\/strong> tra le prime dieci province per numero di reati registrati nel 2023. A incidere sul trend delle denunce sono anche le presenze temporanee o turistiche, che tuttavia non rientrano tra i residenti usati come parametro. Per il sindaco di Napoli, Gaetano Manfredi: <strong>\u00abI reati pi\u00f9 violenti sono dovuti a una circolazione troppo facile delle armi. Bisogna investire in politiche sociali e sanitarie, non solo nei presidi\u00bb.<\/strong><\/p>\n<h4><strong>Le citt\u00e0 pi\u00f9 sicure<\/strong><\/h4>\n<p>In controtendenza rispetto ai grandi centri urbani, le province di <strong>Oristano, Potenza e Treviso<\/strong> risultano essere le <strong>pi\u00f9 sicure d\u2019Italia<\/strong>, posizionandosi in fondo alla classifica. Qui le denunce sono decisamente inferiori, segno di un maggiore controllo del territorio o, come suggerisce Roia, di un fenomeno diverso: una possibile omert\u00e0 o l&#8217;assenza di un\u2019efficace azione dello Stato.<\/p>\n<h4><strong>Le province della Calabria<\/strong><\/h4>\n<p>Cosenza, \u00e8 evidentemente la provincia pi\u00f9 sicura tra quelle calabresi. E&#8217; infatti al <strong>95\u00b0 posto<\/strong> <strong>nell\u2019Indice della Criminalit\u00e0 2024<\/strong> de Il Sole 24 Ore, con 2.560,3 denunce ogni 100mila abitanti. <strong>Catanzaro<\/strong> si piazza al <strong>41\u00b0<\/strong> posto con 3.390,7 reati denunciati. Al <strong>76\u00b0<\/strong> posto troviamo <strong>Crotone<\/strong> con 2.866,5 denunce; <strong>61\u00aa<\/strong>\u00a0posizione per <strong>Vibo Valentia<\/strong> (3.036,6) e <strong>Reggio Calabria<\/strong> \u00e8 all&#8217;80\u00b0 posto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Le grandi metropoli turistiche Milano, Roma e Firenze si confermano anche quest&#8217;anno le peggiori nell\u2019Indice della Criminalit\u00e0 2024 del Sole 24 Ore, la graduatoria su base provinciale che ogni anno permette di scoprire quali sono le province meno sicure. Anche la top 10 \u00e8 popolata da grandi citt\u00e0 e mete turistiche. A livello [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":180527,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-239619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=239619"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/180527"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=239619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=239619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=239619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}