{"id":239742,"date":"2024-09-17T11:27:11","date_gmt":"2024-09-17T09:27:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=239742"},"modified":"2024-09-17T11:27:11","modified_gmt":"2024-09-17T09:27:11","slug":"cosenza-lex-marito-di-ilaria-mirabelli-denuncia-mario-molinari-per-aggressione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-lex-marito-di-ilaria-mirabelli-denuncia-mario-molinari-per-aggressione\/","title":{"rendered":"Cosenza, l&#8217;ex marito di Ilaria Mirabelli denuncia Mario Molinari per aggressione"},"content":{"rendered":"<p>COSENZA &#8211; <strong>L\u2019ex marito di Ilaria Mirabelli<\/strong>, la 38enne morta a Lorica il 25 agosto scorso, ha presentato in Procura a Cosenza un esposto per denunciare<strong> l\u2019aggressione subita da Mario Molinari<\/strong>. L&#8217;uomo, che al momento dell&#8217;incidente si trovava in auto con Ilaria, \u00e8 indagato attualmente per<strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/morte-di-ilaria-mirabelli-mario-molinari-e-indagato-per-omicidio-stradale\" target=\"_blank\" rel=\"noopener\"> omicidio stradale<\/a><\/strong>.<\/p>\n<p>Molinari &#8211; secondo quanto racconta Federico Paladino &#8211; sarebbe entrato nel negozio a Cosenza dove lavora e che gestisce insieme ai fratelli &#8211; a seguito di una lite scoppiata tra i due il giorno precedente &#8211; rompendo il vetro posto sul bancone di vendita e aggredendolo. Molinari, che in quel periodo aveva una relazione con Ilaria, avrebbe colpito Paladino<strong>\u00a0con schiaffi e pugni provocandogli la rottura del mignolo della mano destra<\/strong>.<\/p>\n<p>L&#8217;episodio sarebbe stato ripreso dalle telecamere di videosorveglianza poste all&#8217;interno del negozio. <strong>L\u2019avvocato Salvatore <\/strong>Tropea &#8211; che assiste Federico Paladino<strong> &#8211; <\/strong>Tropea tra qualche giorno produrr\u00e0 copia dell\u2019esposto anche ai due pubblici ministeri, Donatella Donato e Mariangela Farro, che conducono l\u2019inchiesta sul decesso di Ilaria Mirabelli.<\/p>\n<p>Dalle indagini e dalle testimonianze sull&#8217;incidente <strong>iniziano a trapelare diverse informazioni<\/strong>: Molinari ha sempre sostenuto di non essere lui alla guida nel giorno della tragedia mentre sono i <strong>due i testimoni<\/strong> che dichiarano che era lui a condurre l&#8217;auto.<\/p>\n<p>Intanto gli inquirenti hanno <strong>disposto accertamenti sui due telefoni cellulari<\/strong> sequestrati dai carabinieri dopo l&#8221;incidente: la perizia verr\u00e0 avviata luned\u00ec 23, mentre venerd\u00ec 20 sar\u00e0 il consulente tecnico gi\u00e0 nominato a eseguire una perizia sulla vettura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L\u2019ex marito di Ilaria Mirabelli, la 38enne morta a Lorica il 25 agosto scorso, ha presentato in Procura a Cosenza un esposto per denunciare l\u2019aggressione subita da Mario Molinari. L&#8217;uomo, che al momento dell&#8217;incidente si trovava in auto con Ilaria, \u00e8 indagato attualmente per omicidio stradale. Molinari &#8211; secondo quanto racconta Federico Paladino [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":239046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-239742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=239742"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/239046"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=239742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=239742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=239742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}