{"id":239764,"date":"2024-10-20T01:53:52","date_gmt":"2024-10-19T23:53:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=239764"},"modified":"2024-10-20T01:54:17","modified_gmt":"2024-10-19T23:54:17","slug":"la-gravidanza-modifica-lanatomia-del-cervello-la-scoperta-pubblicata-su-nature-video","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/la-gravidanza-modifica-lanatomia-del-cervello-la-scoperta-pubblicata-su-nature-video\/","title":{"rendered":"La gravidanza modifica l\u2019anatomia del cervello: la scoperta pubblicata su Nature &#8211; VIDEO"},"content":{"rendered":"<p>COSENZA &#8211;<strong> La gravidanza modifica l\u2019anatomia del cervello<\/strong>, lasciando\u00a0<strong>immutate solo poche aree<\/strong>; tutte\u00a0<strong>le altre si restringono e contemporaneamente al loro interno si rafforzano le connessioni fra le cellule nervose<\/strong><\/p>\n<p>La scoperta,\u00a0<a href=\"https:\/\/www.nature.com\/articles\/s41593-024-01741-0\" rel=\"noopener\">pubblicata\u00a0<\/a>sulla rivista Nature Neuroscience,<strong>\u00a0\u00e8 la prima osservazione continuativa della plasticit\u00e0 e della capacit\u00e0 di adattamento del pi\u00f9 complesso degli organi<\/strong>. \u201cFinora\u00a0<strong>non avevamo mai visto il cervello nel bel mezzo di questa metamorfosi<\/strong>\u201d, ha detto la coordinatrice della ricerca Emily Jacobs, dell\u2019Universit\u00e0 della California a Santa Barbara, nella conferenza stampa online organizzata da Nature. La prima autrice \u00e8 Laura Pritschet, della stessa universit\u00e0.<\/p>\n<div class=\"rich-text\" contenteditable=\"false\">\n<div class=\"enrichment enrichment-image\">\n<figure class=\"image\">\n<div id=\"standard_3\" class=\"st-placement standard_3 inImageRestricted\">\n<div class=\"st-adunit st-adunit-tagged st-reset st-show\">\n<div class=\"st-adunit-ad st-reset\">\n<div class=\"st-display-render st-reset open 300x600\">\n<div class=\"st-canvas st-reset vertical-static\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"ratio\"><img decoding=\"async\" src=\"https:\/\/www.ansa.it\/webimages\/img_621x414\/2024\/9\/17\/6a46ac67e41e52a2654b47c42a49a90d.png\" alt=\"\" title=\"\"><\/span><\/p>\n<div class=\"bottom\"><span class=\"figcaption\">Rappresentazione grafica dei camiamenti avvenuti nel cervello durante la gravidanza (fonte: Laura Pritschet)<\/span><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Mentre\u00a0<strong>il volume della materia grigia si riduce in modo pronunciato<\/strong>,\u00a0<strong>cos\u00ec come lo spessore della corteccia<\/strong>,\u00a0<strong>la struttura della materia bianca diventa pi\u00f9 solida<\/strong>\u00a0e lo stesso avviene nel\u00a0<strong>liquido cerebrospinale<\/strong>\u00a0(cefalorachidiano) e nelle cavit\u00e0 (<strong>ventricoli<\/strong>) nelle quali questo viene prodotto.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"rich-text\" contenteditable=\"false\">\n<div class=\"enrichment enrichment-image\">\n<figure class=\"image\">\n<div id=\"standard_6\" class=\"st-placement standard_6 inImageRestricted\">\n<div class=\"st-adunit st-adunit-tagged st-reset st-show\">\n<div class=\"st-adunit-ad st-reset\"><\/div>\n<\/div>\n<\/div>\n<p><span class=\"ratio\"><img decoding=\"async\" src=\"https:\/\/www.ansa.it\/webimages\/img_621x414\/2024\/9\/17\/3ce6bae8cd7ccf5ae7946c7e1363880a.png\" alt=\"\" title=\"\"><\/span><\/p>\n<div class=\"bottom\"><span class=\"figcaption\">Rappresentazione grafica dei cambiamenti nel volume della materia grigia durante la gravidanza avanzata (fonte: Laura Pritsche)<\/span><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Sono cambiamenti che regradiscono nel tempo, anche se non \u00e8 chiaro in quali tempi: alcuni sono stti osservati anche a due anni dal parto.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/7GVg05SGxGE?si=dRN8WgyiQtbccTnL\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>Da quelle che erano immagini fisse e frammentarie del cervello durante la gravidanza, si \u00e8 passati cos\u00ec a\u00a0<strong>una sorta dil film nel quale i cambiamenti sono evidenti<\/strong>. E&#8217; stato possibile grazie alle\u00a0<strong>immagini del cervello di una donna di 38 anni\u00a0<\/strong>ottenute con la\u00a0<strong>risonanza magnetica<\/strong>\u00a0e rilevate\u00a0<strong>da tre mesi prima del concepimento a due anni dopo il parto<\/strong>. Le immagini sono state poi confrontate con quelle di otto individui di controllo e combinate con altri dati, come quelli ottenuti dalle analisi del sangue. Il risultato di questo &#8220;tour de force\u201d, come l&#8217;ha definito la ricercatrice, \u00e8 la prima mappa completa del modo in cui la gravidanza modella il cervello,\u00a0<strong>liberamente accessibile alla comunit\u00e0 scientifica<\/strong>.<\/p>\n<div class=\"rich-text\" contenteditable=\"false\">\n<div class=\"enrichment enrichment-image\">\n<figure class=\"image\"><span class=\"ratio\"><img decoding=\"async\" src=\"https:\/\/www.ansa.it\/webimages\/img_621x414\/2024\/9\/17\/89fa2777199b44865ff8fd5217853604.png\" alt=\"\" title=\"\"><\/span><\/p>\n<div class=\"bottom\"><span class=\"figcaption\">Cambiamenti nella microstruttura della materia bianca (fonte: Daniela Cossio)<\/span><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>E&#8217; anche \u00e8 un\u00a0<strong>contributo importante alla medicina di genere<\/strong>. &#8220;Le scienze biomediche hanno storicamente ignorato la salute delle donne&#8221;, ha detto Jacobs. Ma \u00e8 chiaro che \u00e8 solo un primo passo.<\/p>\n<p><strong>E&#8217; solo l&#8217;inizio<\/strong>\u00a0anche sul fronte scientifico: &#8220;<strong>questo articolo apre pi\u00f9 domande che risposte<\/strong>, perch\u00e9 in realt\u00e0\u00a0<strong>stiamo solo iniziando a scalfire la superficie<\/strong>&#8220;, ha osservato la ricercatrice. \u201cE\u2019 un\u00a0<strong>campo di ricerca appena aperto<\/strong>\u201d: saranno necessari\u00a0<strong>nuovi studi per capire l\u2019impatto a lungo termine della gravidanza sul cervello<\/strong>, bisogner\u00e0 fare\u00a0<strong>ricerche su una popolazione pi\u00f9 ampia<\/strong>, si potranno\u00a0<strong>esplorare eventuali implicazioni sulla salute mentale<\/strong>\u00a0nel periodo intorno alla nascita, come la\u00a0<strong>depressione post-partum<\/strong>, sull&#8217;<strong>invecchiamento cerebrale<\/strong>\u00a0o su disturbi come l&#8217;<strong>emicrania<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La gravidanza modifica l\u2019anatomia del cervello, lasciando\u00a0immutate solo poche aree; tutte\u00a0le altre si restringono e contemporaneamente al loro interno si rafforzano le connessioni fra le cellule nervose La scoperta,\u00a0pubblicata\u00a0sulla rivista Nature Neuroscience,\u00a0\u00e8 la prima osservazione continuativa della plasticit\u00e0 e della capacit\u00e0 di adattamento del pi\u00f9 complesso degli organi. \u201cFinora\u00a0non avevamo mai visto il [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":239765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22],"tags":[],"class_list":["post-239764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dal-mondo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=239764"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/239765"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=239764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=239764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=239764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}