{"id":239794,"date":"2024-09-17T21:00:23","date_gmt":"2024-09-17T19:00:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=239794"},"modified":"2024-09-17T19:46:38","modified_gmt":"2024-09-17T17:46:38","slug":"autonomia-differenziata-caruso-ad-occhiuto-aderisca-al-referendum-gliene-rendero-merito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/autonomia-differenziata-caruso-ad-occhiuto-aderisca-al-referendum-gliene-rendero-merito\/","title":{"rendered":"Autonomia Differenziata, Caruso ad Occhiuto: &#8220;aderisca al Referendum, gliene render\u00f2 merito&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Ancora una volta il <strong>direttore della Svimez<\/strong>, Luca Bianchi, interviene con fermezza sull&#8217;Autonomia Differenziata definendola, per come proposta, &#8221; <strong>una truffa<\/strong>&#8220;. Una definizione che mi trova perfettamente d&#8217;accordo in quanto, per dirla in poche parole, non si prevede neanche un euro per attuarla e colmare il divario tra Nord e Sud. Un&#8217;operazione, quest&#8217;ultima, per la quale servirebbero, sempre secondo fondi Svimez, circa 80 miliardi di euro&#8221;.<\/p>\n<p>Sono le parole del sindaco di Cosenza, Franz Caruso che prosegue: &#8221; Il governatore del Veneto ha gi\u00e0 avanzato richiesta di maggior autonomia nelle nove materie &#8220;non lepizzabili&#8221; tra cui, rapporti internazionali e con l&#8217;Ue della Regione, commercio con l&#8217;estero, Professioni; Protezione civile; Previdenza complementare e integrativa; Coordinamento della finanza pubblica e del sistema tributario che, se confermata, penalizzer\u00e0 certamente il Mezzogiorno ma contestualmente avvier\u00e0 alla disfatta l&#8217;intero Paese che vedr\u00e0 ridotta complessivamente la sua competitivit\u00e0&#8221;.<\/p>\n<p>&#8220;<strong>Aprire<\/strong>, infatti, <strong>ad egoismi territoriali significa inevitabilmente venire meno alle politiche di integrazione territoriali e produttive<\/strong> che rispondono ad un modello di sviluppo europeo nonch\u00e9 globale. Tutto ci\u00f2, ovviamente a voler tacere del pericolo oggettivo di veder <strong>nascere 20 piccole repubblichette<\/strong> ed al venir meno dei dettami di solidariet\u00e0 politica, economica e sociale decantati nella nostra Carta Costituzionale&#8221;.<\/p>\n<p>Caruso si rivolge quindi al governatore &#8220;ribadendo che tale tema non pu\u00f2 rappresentare terreno di scontro politico\/ideologico, tanto meno di contrapposizione territoriale, ritengo che <strong>Roberto Occhiuto deve ora reagire concretamente<\/strong>, passando dalle parole ai fatti. Nel mentre altre regioni, tra cui Emilia Romagna e Toscana, hanno chiesto il Referendum per l&#8217;abrogazione delle scellerata legge leghista, il <strong>presidente Occhiuto deve necessariamente fare chiarezza sulla sua posizione politica.<\/strong> Non basta pi\u00f9 esprimere dissenso in qualche manifestazione pubblica, seppur apprezzabile. Oggi \u00e8 il tempo dei fatti. Aderisca Roberto Occhiuto al Referendum, sar\u00f2 il primo a rendergliene merito&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Ancora una volta il direttore della Svimez, Luca Bianchi, interviene con fermezza sull&#8217;Autonomia Differenziata definendola, per come proposta, &#8221; una truffa&#8220;. Una definizione che mi trova perfettamente d&#8217;accordo in quanto, per dirla in poche parole, non si prevede neanche un euro per attuarla e colmare il divario tra Nord e Sud. Un&#8217;operazione, quest&#8217;ultima, [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":239795,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-239794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=239794"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/239795"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=239794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=239794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=239794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}