{"id":239859,"date":"2024-09-18T15:17:03","date_gmt":"2024-09-18T13:17:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=239859"},"modified":"2024-09-18T15:17:03","modified_gmt":"2024-09-18T13:17:03","slug":"rende-concluso-il-progetto-educamediamocisulluso-consapevole-e-responsabile-dei-media","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rende-concluso-il-progetto-educamediamocisulluso-consapevole-e-responsabile-dei-media\/","title":{"rendered":"Rende, concluso il progetto \u201cEducamediamoci\u201dsull\u2019uso consapevole e responsabile dei media"},"content":{"rendered":"<p>RENDE &#8211; Con il convegno finale di presentazione dei risultati, si \u00e8 concluso il progetto \u201c<strong>Educamediamoci\u201d,<\/strong> elaborato dall<strong>\u2019Ufficio Politiche Sociali del Comune di Rend<\/strong>e e finanziato dal <strong>Dipartimento per le Politiche della Famiglia della Presidenza del Consiglio dei Ministri<\/strong>, a valere sull\u2019Avviso pubblico per il <strong>finanziamento di progetti per la protezione ed il sostegno di minori vittime di abuso e sfruttamento sessuale<\/strong>, come quarto miglior progetto in tutta Italia.<\/p>\n<p>Il convegno si \u00e8 svolto nel<strong> Museo del Presente di Rende nella giornata di gioved\u00ec 12 settembre,<\/strong> alla presenza del Commissario Prefettizio, Santi Giuffr\u00e8; del Dirigente dei Servizi Sociali, Beniamino Caparra e della P.O. Annalisa Frangella; della Dirigente dell\u2019Istituto Scolastico Rende Quattromiglia, Maria Cristina Rippa e del v. presidente Consiglio di Istituto, Luca Parisoli; della docente Unical, Silvia Sivini, moderato dal coordinatore del progetto, Davide Franceschiello.<\/p>\n<p>Ma i veri protagonisti del convegno sono stati ancora una volta gli studenti, i loro genitori ed i docenti dei laboratori che, attraverso le loro testimonianze ed i loro elaborati, hanno fatto rivivere i momenti salienti del progetto. <strong>Agli studenti sono stati infine distribuiti dei gadget informatici, il vademecum ed il video gioco da loro elaborato e precedentemente dei buoni per l\u2019acquisto di materiale didattico e attrezzature informatiche<\/strong>. Un modo molto concreto ed efficace per sviluppare formazione, sensibilizzazione su determinate tematiche e nel contempo discreto nel sostegno alle famiglie. \u201cEducamediamoci\u201d ha visto la partecipazione degli<strong> studenti dell\u2019Istituto comprensivo Rende Quattromiglia di Rende<\/strong>, impegnati in due laboratori di: Media Education (per fornire agli studenti gli strumenti per una maggiore comprensione sia dei media, sia del proprio rapporto con i mezzi di comunicazione e realizzare un vademecum di buone pratiche per l\u2019utilizzo del web) e di Alfabetizzazione digitale (per mettere in pratica le competenze per la realizzazione di una pagina internet ed un videogioco).<\/p>\n<p>Il tutto finalizzato all\u2019u<strong>tilizzo consapevole e responsabile dei media oltre che a valorizzare il loro ruolo attraverso una partecipazione attiva nello sviluppo di iniziative di contrasto al fenomeno<\/strong>. Tali laboratori sono stati preceduti da una indagine condotta dal Dipartimento di Scienze Politiche e Sociali dell\u2019Universit\u00e0 della Calabria, il cui obiettivo era quello di indentificare la dimensione del fenomeno, in particolare dell\u2019utilizzo dei media da parte dei ragazzi e la loro percezione dei rischi on line, ma anche per indirizzare le strategie formative ed educative dei docenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Con il convegno finale di presentazione dei risultati, si \u00e8 concluso il progetto \u201cEducamediamoci\u201d, elaborato dall\u2019Ufficio Politiche Sociali del Comune di Rende e finanziato dal Dipartimento per le Politiche della Famiglia della Presidenza del Consiglio dei Ministri, a valere sull\u2019Avviso pubblico per il finanziamento di progetti per la protezione ed il sostegno di [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":239860,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-239859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=239859"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/239859\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/239860"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=239859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=239859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=239859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}