{"id":24030,"date":"2013-07-03T14:10:43","date_gmt":"2013-07-03T12:10:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=24030"},"modified":"2023-01-17T13:21:35","modified_gmt":"2023-01-17T12:21:35","slug":"9618-re-alarico-approda-sul-corriere-della-sera-l-orgoglio-di-occhiuto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9618-re-alarico-approda-sul-corriere-della-sera-l-orgoglio-di-occhiuto\/","title":{"rendered":"Re Alarico approda sul Corriere della Sera, l&#8217;orgoglio di Occhiuto"},"content":{"rendered":"<p>COSENZA &#8211; Il condottiero dei Visigoti che saccheggi\u00f2 Roma porta Cosenza sulle colonne del quotidiano nazionale.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Il sindaco Mario Occhiuto interviene sull\u2019articolo del Corriere della Sera a firma di Gian Antonio Stella relativo al progetto del Museo di Alarico affermando \u201cche una grande firma del giornalismo italiano come Gian Antonio Stella dedichi attenzione al progetto del Comune di Cosenza sul Museo di Alarico, con un approfondito articolo pubblicato sulle colonne del Corriere della Sera, ponendo cos\u00ec in risalto la ricchezza storico-culturale legata al nome della citt\u00e0, insieme al fermento del dibattito in corso, \u00e8 per noi motivo di orgoglio e non possiamo quindi che esserne lusingati\u201d. Il sindaco Mario Occhiuto commenta con favore l\u2019odierno servizio del Corsera a pag. 32, intitolato : \u201cL\u2019ultimo oltraggio del barbaro Alarico: \u00e8 lite sul museo\u201d, precisando tuttavia la posizione dell\u2019Esecutivo in merito alle polemiche che vi vengono evidenziate. \u201cFin dalla nostra idea di demolire un ecomostro degli anni \u201950 quale l\u2019ex hotel Jolly \u2013 spiega il sindaco Occhiuto \u2013 cogliendo l\u2019occasione di far sorgere al suo posto un presidio del sapere che restituisca dignit\u00e0 paesaggistica alla suggestiva confluenza dei fiumi di uno dei centri storici pi\u00f9 belli del Paese, abbiamo sempre affermato che l\u2019intento \u00e8 quello di eliminare un elemento incoerente e di disturbo dell\u2019architettura del Centro storico di Cosenza, di riqualificare un\u2019area che introduce sia fisicamente che visivamente nel Centro storico, di riconnettere la parte nuova della citt\u00e0 a quella antica incentivando la frequentazione turistica e cittadina di un luogo cardine non soltanto dal punto di vista urbanistico, ma anche dal punto di vista storico, sociale e, in prospettiva, economico. Di recuperare, ancora, spazi da destinare alla mobilit\u00e0 sostenibile \u2018da\u2019 e \u2018per\u2019 il Centro storico, nonch\u00e9 di chiudere a sud il Mab (Museo all\u2019Aperto Bilotti), che costituisce la spina dorsale artistica e culturale della citt\u00e0 nuova e la cui testata nord \u00e8 rappresentata dal Museo di arte contemporanea di Piazza Bilotti, con annesso parcheggio multipiano interrato. E\u2019 dunque con questo obiettivo che abbiamo pensato, alla confluenza dei fiumi, una piazza elevata che potesse evocare il mito del tesoro di Alarico in modo da farne un brand di attrazione turistica e di conseguenza di crescita economica. Del resto, la frequente presenza di visitatori tedeschi che da queste parti arrivano perch\u00e9 spinti dalla curiosit\u00e0 di seguire le orme del celebre antenato, per quanto eroe negativo, \u00e8 cosa risaputa. Siamo convinti che la politica debba saper cogliere certi stimoli ai fini dei margini di sviluppo di un territorio, sfruttandoli in positivo come gi\u00e0 comunque hanno fatto Comuni che su personaggi storici o letterari hanno costruito una fortuna. L\u2019operazione che abbiamo in programma \u2013 aggiunge Occhiuto &#8211; e per la quale abbiamo intercettato un finanziamento di 7milioni di euro, non vuole celebrare la figura di Alarico quale barbaro sanguinario e saccheggiatore, bens\u00ec cavalcare la leggenda del famoso tesoro che sarebbe sepolto, secondo le antiche cronache, alla confluenza fra il Crati e il Busento. A monte di tutto ci\u00f2, come detto, c\u2019\u00e8 soprattutto la bonifica di un sito che vede la presenza di un edificio non coerente con il paesaggio che lo circonda, oltre che la riqualificazione generale della zona. Pertanto \u2013 conclude il sindaco Mario Occhiuto \u2013 ringrazio Gian Antonio Stella per aver portato alla ribalta nazionale quello che sar\u00e0 uno dei fiori all\u2019occhiello della citt\u00e0 creativa che, con ambizione, stiamo provando a realizzare in modo da lasciare in eredit\u00e0 una Cosenza pi\u00f9 bella e pi\u00f9 vivibile\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il condottiero dei Visigoti che saccheggi\u00f2 Roma porta Cosenza sulle colonne del quotidiano nazionale.<\/p>\n","protected":false},"author":22,"featured_media":24031,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-24030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=24030"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/24031"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=24030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=24030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=24030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}