{"id":240308,"date":"2024-09-24T17:00:00","date_gmt":"2024-09-24T15:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=240308"},"modified":"2024-09-24T16:30:21","modified_gmt":"2024-09-24T14:30:21","slug":"cristina-mazzotti-la-18enne-sequestrata-e-chiusa-in-una-buca-a-processo-4-imputati-legati-alla-ndrangheta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cristina-mazzotti-la-18enne-sequestrata-e-chiusa-in-una-buca-a-processo-4-imputati-legati-alla-ndrangheta\/","title":{"rendered":"Cristina Mazzotti: la 18enne sequestrata e chiusa in una buca. A processo 4 imputati legati alla &#8216;ndrangheta"},"content":{"rendered":"<p>COMO &#8211; A oltre <strong>49 anni di distanza,<\/strong> domani in Corte di Assise a Como si riapre i<strong>l processo sul sequestro e l&#8217;omicidio di Cristina Mazzott<\/strong>i, la diciottenne rapita a Eupilio (Como) il primo<strong> luglio 1975 mentre rientrava a casa da una festa con amici<\/strong>, <strong>morta durante la detenzione 25 giorni pi\u00f9 tardi<\/strong> e il cui corpo fu abbandonato in una discarica di Galliate (Novara), dove fu trovato il primo settembre di quell&#8217;anno. Cristina fu tenuta prigioniera all&#8217;interno di in una <b>buca <\/b>di un garage<strong>, da cui usciva all&#8217;esterno <\/strong><b>un\u00a0 piccolo tubo di plastica di appena 5 cm <\/b>per respirare. Venne nutrita dalla sua carceriera, Loredana Petroncini, con due panini al giorno e le venne<strong> somministrato Valium ogni giorn<\/strong>o.\u00a0La ragazza\u00a0<b>mor\u00ec in modo atroce tra il 30 luglio e il 1\u00ba agosto<\/b>.<\/p>\n<h3>Il padre pag\u00f2 il riscatto di oltre 1 miliardo<\/h3>\n<p>I resti del suo corpo senza vita verranno ritrovati solo nel mese di settembre nella discarica di Varallino, vicino a Sesto Calende: l\u2019autopsia accert\u00f2 che si trovava l\u00ec da almeno 40 giorni. <strong>Ci vollero alcuni mesi, seguendo a ritroso la pista dei soldi del riscatto pagato dai genitori (oltre un miliardo di lire), per catturare tutta la banda<\/strong>. Le indagini dell&#8217;epoca portarono il Tribunale di Novara ad emettere nel 1977 a<b>\u00a013 condanne, di cui 8 all\u2019ergastolo<\/b>: tra carcerieri, centralinisti, riciclatori del secondo gruppo lombardo di fiancheggiatori. Senza tuttavia arrivare a individuare\u00a0<b>nessuno del gruppo di esecutori materiali calabresi<\/b>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Mazzotti2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-240311 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Mazzotti2.jpg\" alt=\"Mazzotti2\" width=\"573\" height=\"360\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Mazzotti2.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Mazzotti2-300x188.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Mazzotti2-768x482.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Mazzotti2-669x420.jpg 669w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Mazzotti2-150x94.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Mazzotti2-696x437.jpg 696w\" sizes=\"auto, (max-width: 573px) 100vw, 573px\" \/><\/a><\/p>\n<h3>Il primo sequestro di una donna<\/h3>\n<p>Fu il primo sequestro di una donna e per l&#8217;intera vicenda sono state gi\u00e0 condannate tredici persone, ma nei processi non entrarono mai gli esecutori materiali e i mandanti, questi ultimi si ritiene uomini affiliati alla &#8216;ndrangheta calabrese. <strong>A processo domani per il reato di omicidio come conseguenza di sequestro di persona, comparir\u00e0 Giuseppe Morabito, il boss quasi ottantenne della &#8216;ndrangheta residente nel Varesotto, Giuseppe Calabr\u00f2 detto &#8220;U&#8217; Dutturicchio&#8221;, 70 anni, Antonio Talia, 73 anni, precedenti per armi e droga, e Demetrio Latella, 70 anni, reo confesso del sequestro<\/strong>.<\/p>\n<h3>Caso riaperto dopo la\u00a0richiesta dell&#8217;avvocato Fabio Repici<\/h3>\n<p><strong>Sull&#8217;auto su cui viaggiava la ragazza venne trovata un&#8217;impronta di una persona estranea, impronta che soltanto nel 2006 fu possibile attribuire a Latella<\/strong>, il quale confess\u00f2 di avere partecipato al sequestro e fece i nomi degli altri due a processo domani. Nel 2011 tuttavia il fascicolo a carico di Latella venne archiviato. <strong>Ora \u00e8 stato riaperto grazie alla richiesta dell&#8217;avvocato Fabio Repici, che assiste i familiari del giudice Bruno Caccia, ucciso da un agguato di &#8216;ndrangheta a Torino nel 1983<\/strong>. Nell&#8217;inchiesta Caccia era stato coinvolto Latella, la cui posizione fu poi archiviata. Il legale, cercando informazioni su Latella, <strong>si imbatt\u00e8 nella vicenda Mazzotti<\/strong>\u00a0e, ritenendo non fondate le ragioni dell&#8217;archiviazione nell&#8217;inchiesta sul rapimento, chiese la riapertura del caso, che l&#8217;anno scorso \u00e8 stata accolta dalla gup Angela Minerva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COMO &#8211; A oltre 49 anni di distanza, domani in Corte di Assise a Como si riapre il processo sul sequestro e l&#8217;omicidio di Cristina Mazzotti, la diciottenne rapita a Eupilio (Como) il primo luglio 1975 mentre rientrava a casa da una festa con amici, morta durante la detenzione 25 giorni pi\u00f9 tardi e il [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":240309,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-240308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=240308"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/240309"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=240308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=240308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=240308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}