{"id":240393,"date":"2024-09-25T13:27:01","date_gmt":"2024-09-25T11:27:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=240393"},"modified":"2024-09-25T13:53:48","modified_gmt":"2024-09-25T11:53:48","slug":"ti-volevo-dedicare-a-cosenza-il-friendly-match-dedicato-a-salvatore-figliuzzi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ti-volevo-dedicare-a-cosenza-il-friendly-match-dedicato-a-salvatore-figliuzzi\/","title":{"rendered":"&#8216;Ti volevo dedicare&#8217;, a Cosenza il friendly match dedicato a Salvatore Figliuzzi"},"content":{"rendered":"<p>COSENZA &#8211;<strong> &#8216;TI VOLEVO DEDICARE&#8217;, \u00e8 un friendly match dedicato a Salvatore Figliuzzi, il ragazzo di 18 anni deceduto per un malore, mentre stava giocando a calcetto con gli amici, nel campetto dietro la vecchia stazione di Cosenza.\u00a0<\/strong>\u00a0A distanza di 5 anni, <strong>Domenica 29 Settembre 2024,<\/strong> amici e parenti si ritroveranno al <strong>Palaferraro di Cosenza<\/strong> per un amichevole di calcetto, dando spazio anche ai pi\u00f9 piccoli. Coinvolta in questa iniziativa anche l\u2019Accademia calcio Cosenza e la A.S.D Nemo calcio, associazione di ragazzi diversamente abili. &#8220;Sar\u00e0 una giornata dedicata allo sport e al divertimento, una giornata proprio come avrebbe voluto Lui!&#8221;, aggiungono i parenti e amici di Salvatore Figliuzzi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-240395 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/461045836_535912349123391_2582684472443864410_n.jpg\" alt=\"Ti volevo dedicare\" width=\"579\" height=\"579\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/461045836_535912349123391_2582684472443864410_n.jpg 720w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/461045836_535912349123391_2582684472443864410_n-300x300.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/461045836_535912349123391_2582684472443864410_n-150x150.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/461045836_535912349123391_2582684472443864410_n-420x420.jpg 420w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/461045836_535912349123391_2582684472443864410_n-696x696.jpg 696w\" sizes=\"auto, (max-width: 579px) 100vw, 579px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8216;TI VOLEVO DEDICARE&#8217;, \u00e8 un friendly match dedicato a Salvatore Figliuzzi, il ragazzo di 18 anni deceduto per un malore, mentre stava giocando a calcetto con gli amici, nel campetto dietro la vecchia stazione di Cosenza.\u00a0\u00a0A distanza di 5 anni, Domenica 29 Settembre 2024, amici e parenti si ritroveranno al Palaferraro di Cosenza [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":240395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-240393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=240393"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/240395"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=240393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=240393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=240393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}