{"id":240491,"date":"2024-09-28T07:00:53","date_gmt":"2024-09-28T05:00:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=240491"},"modified":"2024-09-26T12:04:12","modified_gmt":"2024-09-26T10:04:12","slug":"superbonus-110-lavori-mai-partiti-e-cantieri-interrotti-codici-al-fianco-di-cittadini-e-piccole-imprese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/superbonus-110-lavori-mai-partiti-e-cantieri-interrotti-codici-al-fianco-di-cittadini-e-piccole-imprese\/","title":{"rendered":"Superbonus 110%: lavori mai partiti e cantieri interrotti. Codici al fianco di cittadini e piccole imprese"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Una serie infinita di problemi e situazioni critiche<\/strong> che non sembrano avere sbocchi. Sono le conseguenze con cui molti, <strong>tra condomini e privati, stanno facendo i conti per quanto riguarda il Superbonus 110%<\/strong>. L\u2019<a href=\"https:\/\/quicosenza.it\/news\/italia\/379546-economia-m5s-grazie-al-superbonus-110-nasce-ledilizia-amica-dellambiente\" target=\"_blank\" rel=\"noopener\">iniziativa<\/a> di incentivazione edilizia, voluta dall&#8217;allora Governo Conte, per<strong> incentivare la riqualificazione energetica e antisismica<\/strong> degli immobili, <strong>non ha portato sempre ai benefici prospettati<\/strong>.<\/p>\n<p>Lo dimostrano non solo le c<strong>entinaia di truffe scoperte dalla Guardia Di Finanza<\/strong>, ma anche le difficolt\u00e0 nella cessione dei crediti,<strong>\u00a0l&#8217;enorme<a href=\"https:\/\/quicosenza.it\/news\/italia\/superbonus-addio-a-sconto-in-fattura-e-cessione-del-credito-una-misura-sanguinosa-a-beneficio-di-pochi\" target=\"_blank\" rel=\"noopener\"> voragine<\/a> nei conti pubblici<\/strong> e <strong>le segnalazioni raccolte dagli <a href=\"https:\/\/quicosenza.it\/news\/italia\/danni-del-superbonus-lassociazione-codici-attiva-uno-sportello-legale\" target=\"_blank\" rel=\"noopener\">Sportelli<\/a> dell\u2019associazione Codici<\/strong>, che si \u00e8 attivata per fornire assistenza a cittadini e titolari di piccole imprese.<\/p>\n<h3>Superbonus 110%: problematiche complesse<\/h3>\n<p>\u201c<strong>Il Superbonus 110% ha provocato problematiche particolarmente complesse<\/strong> \u2013 afferma Ivano Giacomelli, Segretario Nazionale di <a href=\"https:\/\/codici.org\/\" rel=\"noopener\">Codici<\/a> \u2013 ed <strong>anche danni economici rilevanti<\/strong>. Tra i principali casi registrati ci sono <strong>lavori mai partiti, cantieri interrotti o interventi che non hanno apportato i benefici previsti<\/strong>. A questo si aggiungono le <strong>questioni di natura fiscale, a partire dalle difficolt\u00e0 nel procedere alla cessione del credito nei confronti delle banche&#8221;<\/strong>.<\/p>\n<p>&#8220;Se a tutto ci\u00f2 sommiamo i <strong>continui mutamenti della normativa di riferimento<\/strong>, \u00e8 facile intuire il caos che si \u00e8 generato. C<strong>ome associazione ci siamo attivati per fornire assistenza legale a chi ha problemi con il Superbonus 110%<\/strong>. La materia non \u00e8 semplice. Spesso le situazioni sono anche delicate, soprattutto per chi ha pagato di tasca propria per rimediare a lavori incompleti o realizzati male. \u00c8<strong> possibile, per\u00f2, trovare una soluzione ed \u00e8 il compito che ci siamo prefissati con i nostri esperti\u201d<\/strong>. I cittadini ed i titolari di piccole imprese danneggiati dal Superbonus 110% possono rivolgersi all\u2019a<strong>ssociazione Codici telefonando al numero 065571996<\/strong> oppure inviando un\u2019e-mail all\u2019indirizzo <a href=\"http:\/\/segreteria.sportello@codici.org\" target=\"_blank\" rel=\"noopener\">segreteria.sportello@codici.org<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Una serie infinita di problemi e situazioni critiche che non sembrano avere sbocchi. Sono le conseguenze con cui molti, tra condomini e privati, stanno facendo i conti per quanto riguarda il Superbonus 110%. L\u2019iniziativa di incentivazione edilizia, voluta dall&#8217;allora Governo Conte, per incentivare la riqualificazione energetica e antisismica degli immobili, non ha portato [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":240493,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-240491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=240491"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/240493"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=240491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=240491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=240491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}