{"id":240560,"date":"2024-09-27T10:45:26","date_gmt":"2024-09-27T08:45:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=240560"},"modified":"2024-09-27T10:47:25","modified_gmt":"2024-09-27T08:47:25","slug":"sibari-amendolara-e-crotone-aperture-straordinarie-di-parchi-e-musei-a-1-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sibari-amendolara-e-crotone-aperture-straordinarie-di-parchi-e-musei-a-1-euro\/","title":{"rendered":"Sibari, Amendolara e Crotone: aperture straordinarie di Parchi e Musei a 1 euro"},"content":{"rendered":"<p class=\"v1MsoNormal\">COSENZA &#8211; Sono tanti gli appuntamenti programmati dall&#8217;istituto autonomo del Ministero della Cultura per il <strong>fine settimana del 28 e 29 settembre<\/strong> e che permetteranno ai tanti visitatori di scoprire il <strong>&#8220;Patrimonio in cammino&#8221;.<\/strong> Questo, infatti, il tema scelto per il 2024 che riprende lo slogan europeo &#8220;Routes, Networks and Connections&#8221; invitando a riflettere sul valore delle connessioni culturali attraverso cammini, vie di comunicazione e scambi che hanno modellato le nostre identit\u00e0.<\/p>\n<p class=\"v1MsoNormal\">Al\u00a0<b>Museo archeologico nazionale di Crotone<\/b>\u00a0sabato \u00e8 prevista una apertura straordinaria serale fino alle 23:00 con una visita guidata gratuita alle 20:30.\u00a0<b>Al Museo archeologico nazionale di Capo Colonna<\/b>\u00a0sempre sabato \u00e8 calendarizzata una apertura straordinaria serale fino alle 23:00 mentre domenica visita guidata gratuita alle 10:00. Alla\u00a0<b>Fortezza di Le Castella<\/b>, ancora, visita guidata gratuita alle 15:00.\u00a0<b>Al Museo archeologico nazionale di Amendolara<\/b>\u00a0sabato ci sar\u00e0 una apertura straordinaria dalle 15:00 alle 22:00.<\/p>\n<p class=\"v1MsoNormal\">Lungo l&#8217;elenco, infine, delle attivit\u00e0 al\u00a0<b>Museo archeologico nazionale della Sibaritide<\/b>\u00a0dove sabato 28 settembre si terr\u00e0 una visita guidata al Parco del Cavallo e di seguito al Museo, alle 16:00, una apertura straordinaria serale fino alle 23:00; la tradizionale &#8220;Notte in Riserva&#8221;, apertura serale dei depositi con due turni di visite guidate alle 20:00 e alle 21:30. Domenica 29 settembre, invece, laboratorio aperto a tutti sulla ceramica e coroplastica antica, alle 16:00.<\/p>\n<p class=\"v1MsoNormal\">\u00abIl laboratorio \u2013 ha spiegato il Direttore dei Parchi Filippo Demma \u2013 sperimenter\u00e0 la possibilit\u00e0 di realizzare personalmente &#8211; sporcandosi le mani &#8211; vasi in argilla con l&#8217;uso del tornio e statuine secondo le tecniche che erano in uso in Magna Grecia. Conosceremo gli ornamenti degli antichi abitanti della Sibaritide e ne vedremo riproduzioni fedeli\u00bb.<\/p>\n<p class=\"v1MsoNormal\">Mentre tra <strong>le novit\u00e0 di questa edizione<\/strong> <strong>dell&#8217;iniziativa &#8220;Notte in Riserva&#8221;<\/strong> c&#8217;\u00e8 la presentazione di alcuni reperti provenienti dai recenti scavi archeologici realizzati a Torre Mordillo dal team di ricerca guidato da Ilaria Battiloro, Professor of Classical Archaeology in the Departments of Classics and Visual and Material Culture, Mount Allison University, Canada\u00bb.<\/p>\n<p class=\"v1MsoNormal\">Per queste due giornate, infine, sempre nel museo sibarita \u00e8 stata riallestita<strong> la vetrina dedicata all'&#8221;Archeologia Salvata&#8221;<\/strong>, con i reperti trafugati provenienti dai sequestri. Il tema questa volta sar\u00e0 quello delle armi. \u00abIl nostro consueto appuntamento con i reperti provenienti dai materiali sequestrati dal Nucleo Tutela Beni Culturali dei Carabinieri e conservati all&#8217;interno dei magazzini del museo questo autunno \u2013 ha spiegato ancora Demma \u2013 luccica come una punta di freccia. Si tratta di una nuovissima esposizione che ha come argomento un excursus cronologico sulle armi, cominciando dalle punte di freccia litiche di epoca preistorica, fino alla produzione di armi (frecce, lance e giavellotti) realizzate prima in bronzo e successivamente in ferro. I materiali esposti coprono un arco cronologico che va dall&#8217;et\u00e0 del bronzo al medioevo, fino a terminare con due baionette utilizzate durante le due guerre mondiali\u00bb.<\/p>\n<p class=\"v1MsoNormal\">Tutti i dettagli e le modalit\u00e0 di prenotazione sono disponibili sui canali social dei Parchi archeologici di Crotone e Sibari.\u00a0<b>Entrata simbolica ad 1 euro\u00a0<\/b>(escluse le gratuit\u00e0 previste per legge e per i possessori della community card del PAS). Per gli eventi di Sibari e Amendolara: per info e prenotazioni si pu\u00f2 chiamare al numero: 3371603495.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Sono tanti gli appuntamenti programmati dall&#8217;istituto autonomo del Ministero della Cultura per il fine settimana del 28 e 29 settembre e che permetteranno ai tanti visitatori di scoprire il &#8220;Patrimonio in cammino&#8221;. Questo, infatti, il tema scelto per il 2024 che riprende lo slogan europeo &#8220;Routes, Networks and Connections&#8221; invitando a riflettere sul [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":240562,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-240560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=240560"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/240562"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=240560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=240560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=240560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}