{"id":24058,"date":"2013-07-04T11:21:10","date_gmt":"2013-07-04T09:21:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=24058"},"modified":"2023-01-17T13:21:37","modified_gmt":"2023-01-17T12:21:37","slug":"9632-emerge-un-cadavere-dal-torrente-di-reggio-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9632-emerge-un-cadavere-dal-torrente-di-reggio-calabria\/","title":{"rendered":"Emerge un cadavere dal torrente di Reggio Calabria"},"content":{"rendered":"<p style=\"text-align: justify;\">REGGIO CALABRIA \u2013 Alla foce del torrente Calopinace, su segnalazione di un cittadino, e\u2019 stato rinvenuto ieri un cadavere.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Succede nel pieno centro del capoluogo metropolitano calabrese. Il cadavere, inizialmente ritenuto di un barbone, era in stato di decomposizione avanzata, il che rendeva difficoltose le operazioni di identificazione, per di piu\u2019 non essendo stati rinvenuti documenti. Si trattava di un magrebino di eta&#8217; compresa tra i 35 e i 50 anni. La vittima \u00e8 stata identificata: e&#8217; Abdelmajid Ayar, cittadino marocchino di 47 anni. L&#8217;uomo viveva a Reggio Calabria con la moglie e si era allontanato da casa dallo scorso maggio. Ancora l&#8217;ipotesi piu&#8217; accreditata per i carabinieri rimane quella di morte accidentale o naturale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA \u2013 Alla foce del torrente Calopinace, su segnalazione di un cittadino, e\u2019 stato rinvenuto ieri un cadavere.<\/p>\n","protected":false},"author":22,"featured_media":24059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-24058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=24058"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/24059"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=24058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=24058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=24058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}