{"id":240826,"date":"2024-09-30T19:36:04","date_gmt":"2024-09-30T17:36:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=240826"},"modified":"2024-09-30T19:36:04","modified_gmt":"2024-09-30T17:36:04","slug":"longobucco-la-sila-mare-sara-completata-e-riaperta-entro-la-prima-decade-di-dicembre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/longobucco-la-sila-mare-sara-completata-e-riaperta-entro-la-prima-decade-di-dicembre\/","title":{"rendered":"Longobucco, la Sila-Mare sar\u00e0 completata e riaperta entro la prima decade di dicembre"},"content":{"rendered":"<p>LONGOBUCCO (CS) &#8211; <strong>La <a href=\"https:\/\/quicosenza.it\/news\/provincia\/sila-mare-ancora-chiusa-i-cittadini-minacciano-di-riaprirla\" target=\"_blank\" rel=\"noopener\">Sila-Mare<\/a> sar\u00e0 completata e riaperta entro la prima decade di dicembre<\/strong>. Il <strong>rallentamento dei lavori<\/strong> registrato in queste settimane \u00e8 stato determinato dalle<strong> difficolt\u00e0 nel reperimento dei materiali per la messa in sicurezza dei versanti, ma l\u2019intoppo \u00e8 stato gi\u00e0 risolto.<\/strong> I lavori sono pronti a ripartire a strettissimo giro. \u00c8 quanto fa sapere il <strong>Sindaco Giovanni Pirillo<\/strong> che insieme all\u2019assessore ai lavori pubblici Serafino Greco ha ricevuto rassicurazioni direttamente dall\u2019ingegnere Claudio Moroni, direttore generale del Dipartimento infrastrutture e lavori pubblici, incontrato nei giorni scorsi nella Cittadella regionale, a Catanzaro.<\/p>\n<p>Il Primo Cittadino coglie l\u2019occasione per ribadire i ringraziamenti alla Regione Calabria, al Presidente Roberto Occhiuto, all\u2019assessore alle infrastrutture Gianluca Gallo, congiuntamente alla direzione regionale di ANAS Calabria, per l\u2019incessante lavoro di programmazione e pianificazione di questa infrastruttura strategica che, nei prossimi anni vedr\u00e0 il definitivo completamento fino alla Statale 106, a beneficio di tutte le comunit\u00e0 di questa parte della provincia di Cosenza.<\/p>\n<p><strong>L\u2019attenzione sull\u2019opera, strumento insostituibile per il rilancio competitivo dell\u2019entroterra<\/strong> \u2013 conclude Pirillo \u2013 <strong>era e rimane massima.<\/strong> Una volta completata almeno nel tratto vallivo, bypassando di fatto il pi\u00f9 antico e tortuoso tracciato, la<strong> Sila-Mare rappresenter\u00e0 un\u2019opportunit\u00e0 per l\u2019economia agricola<\/strong> e agroalimentare di pregio della Sila greca e la finestra d\u2019ingresso in una delle destinazioni esperienziali pi\u00f9 inedite e ad oggi inesplorate della Calabria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LONGOBUCCO (CS) &#8211; La Sila-Mare sar\u00e0 completata e riaperta entro la prima decade di dicembre. Il rallentamento dei lavori registrato in queste settimane \u00e8 stato determinato dalle difficolt\u00e0 nel reperimento dei materiali per la messa in sicurezza dei versanti, ma l\u2019intoppo \u00e8 stato gi\u00e0 risolto. I lavori sono pronti a ripartire a strettissimo giro. \u00c8 [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":201036,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-240826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=240826"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/201036"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=240826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=240826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=240826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}