{"id":240851,"date":"2024-10-01T10:35:32","date_gmt":"2024-10-01T08:35:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=240851"},"modified":"2024-10-01T11:54:55","modified_gmt":"2024-10-01T09:54:55","slug":"caso-bergamini-via-alle-controrepliche-poi-camera-di-consiglio-e-sentenza-dalessio-nessuna-pressione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/caso-bergamini-via-alle-controrepliche-poi-camera-di-consiglio-e-sentenza-dalessio-nessuna-pressione\/","title":{"rendered":"Caso Bergamini, via alle controrepliche. Poi camera di consiglio e sentenza. D&#8217;Alessio &#8220;nessuna pressione&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; Ultimo dibattimento, nella Corte D&#8217;Assise di Cosenza prima della sentenza sul processo che<strong> m<\/strong>ira a far luce sulla morte di Denis Bergamini il calciatore del Cosenza trovato cadavere nel novembre del 1989. La Corte, presieduta dalla dottoressa Lucente<strong> emetter\u00e0 il verdetto al termine della Camera di Consiglio<\/strong> preceduta dalle <strong>controrepliche del procuratore D\u2019Alessio, il pm Primicerio e degli avvocati di parte civile che difendono la famiglia<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Verita-per-Denis-Sit-in-tifosi3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-240873 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Verita-per-Denis-Sit-in-tifosi3.jpg\" alt=\"Verit\u00e0 per Denis Sit-in tifosi3\" width=\"559\" height=\"346\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Verita-per-Denis-Sit-in-tifosi3.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Verita-per-Denis-Sit-in-tifosi3-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Verita-per-Denis-Sit-in-tifosi3-768x476.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Verita-per-Denis-Sit-in-tifosi3-678x420.jpg 678w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Verita-per-Denis-Sit-in-tifosi3-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Verita-per-Denis-Sit-in-tifosi3-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Verita-per-Denis-Sit-in-tifosi3-356x220.jpg 356w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/a><\/p>\n<p>Mentre <strong>fuori dal Tribunale si sono radunati diversi tifosi del Cosenza<\/strong> con un <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/bergamini-e-il-giorno-della-sentenza-sit-in-dei-tifosi-rossoblu-al-palazzo-di-giustizia-foto\" target=\"_blank\" rel=\"noopener\">sit-in pacifico<\/a>, l&#8217;aula la Corte D&#8217;Assise \u00e8 gremita: oltre all&#8217;unica imputata del processo Isabella Intern\u00f2 e il marito Luciano Conte, presenti anche alcuni ex calciatori del Cosenza Calcio:<strong> Michele Padovano, Ciccio Marino, Alberto Urban, Gigi Simoni, Ugo Napolitano e con loro anche Padre Fedele Bisceglia<\/strong>. In aula <strong>Donata Bergamini con i figli<\/strong>: Andrea, Denis e Alice, il compagno di quest\u2019ultima e una nipote.<\/p>\n<div id=\"attachment_240869\" style=\"width: 578px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Ex-calciatori-Cosenza-Caso-Bergamini1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-240869\" class=\"wp-image-240869\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Ex-calciatori-Cosenza-Caso-Bergamini1.jpg\" alt=\"Ex calciatori Cosenza Caso Bergamini1\" width=\"568\" height=\"377\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Ex-calciatori-Cosenza-Caso-Bergamini1.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Ex-calciatori-Cosenza-Caso-Bergamini1-300x199.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Ex-calciatori-Cosenza-Caso-Bergamini1-768x510.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Ex-calciatori-Cosenza-Caso-Bergamini1-633x420.jpg 633w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Ex-calciatori-Cosenza-Caso-Bergamini1-150x100.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Ex-calciatori-Cosenza-Caso-Bergamini1-696x462.jpg 696w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/a><p id=\"caption-attachment-240869\" class=\"wp-caption-text\">Urban, Padovano, Simoni e Padre Fedele<\/p><\/div>\n<h3>D&#8217;Alessio: &#8220;fare pressioni su questa Corte \u00e8 da stolti&#8221;<\/h3>\n<p>\u00c8 <strong>il Procuratore Capo di Castrovillari D&#8217;Alessio a replicare per primo<\/strong> alle affermazione del legale della Intern\u00f2 <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/bergamini-larringa-difensiva-la-interno-e-innocente-denis-si-e-suicidato-investito-due-volte-dal-camion\" target=\"_blank\" rel=\"noopener\">Angelo Pugliese<\/a> che aveva parlato di <strong>connivenze tra la Procura di Castrovillari e la Famiglia Bergamini<\/strong> per aver voluto un processo a tutti i costi.<strong> \u00ab<\/strong><em>Respingiamo fortemente le allusioni che sono scorrette per legge. Respingiamo fortemente termini &#8216;complicit\u00e0&#8217;<\/em>.<em> La procura<\/em> &#8211; continua D&#8217;Alessio &#8211; <em>si \u00e8 concentrata sui fatti con l&#8217;obiettivo di offrire alla Corte una prospettiva di sentenza. Eliminiamo le suggestioni da questo delicato process<\/em>o&#8221;. <strong>Il procuratore chiosa con forza<\/strong> &#8220;<em>fare pressioni su questa corte \u00e8 da stolti e noi pressioni non ne abbiamo ricevuto<\/em>&#8220;.<\/p>\n<h3>&#8220;La Glicoforina \u00e8 attendibile: c&#8217;\u00e8 una sentenza della Cassazione&#8221;<\/h3>\n<p>&#8220;<em><strong>Si \u00e8 parlato della glicoforina che non piace<\/strong><\/em> &#8211; prosegue D&#8217;Alessio -, <em>ci siamo interrogati, abbiamo discusso a lungo della validit\u00e0, prendendo in considerazione sentenze della Cassazione. Non \u00e8 questione di tecnicismi da scienziati, <strong>abbiamo trovato una sentenza del 2018 della Cassazione che dice: la glicoforina \u00e8 attendibile<\/strong>.\u00a0 Non stiamo inventando, non stiamo suggestionando, ma lo stiamo provando! <strong>Eliminiamo quindi le suggestioni da questo delicato processo<\/strong>&#8220;.\u00a0<\/em><\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Bergamini-Donata-e-avvocato-Anselmo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-240870 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Bergamini-Donata-e-avvocato-Anselmo.jpg\" alt=\"Bergamini Donata e avvocato Anselmo\" width=\"533\" height=\"334\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Bergamini-Donata-e-avvocato-Anselmo.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Bergamini-Donata-e-avvocato-Anselmo-300x188.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Bergamini-Donata-e-avvocato-Anselmo-768x481.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Bergamini-Donata-e-avvocato-Anselmo-670x420.jpg 670w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Bergamini-Donata-e-avvocato-Anselmo-150x94.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Bergamini-Donata-e-avvocato-Anselmo-696x436.jpg 696w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/a><\/p>\n<h3>Primicerio &#8220;la questione retromarcia non ha alcuna importanza&#8221;<\/h3>\n<p>La parola \u00e8 passata poi al <strong>Pm Primicerio<\/strong>. &#8220;<em><strong>La questione retromarcia non ha alcuna importanza<\/strong><\/em>&#8221; esordisce il Pubblico Ministero salernitano davanti alla corte di Cosenza in risposta all&#8217;arringa di ieri della difesa Intern\u00f2, la quale sostiene che il povero Denis <strong>venne travolto dal camion non una una sola volta ma due<\/strong>. Una quando Bergamini venne parzialmente arrotato dal camion, la seconda, dopo che era <strong>gi\u00e0 morto, sormontato anche in posizione diversa, quando il mezzo di Pisano fece retromarcia con una sterzata<\/strong>.<\/p>\n<p>&#8220;<em><strong>Nel 2017 \u00e8 stato detto che Bergamini \u00e8 stato soffocato in mano di terzi<\/strong>, era in limine vitae o gi\u00e0 morto con alta probabilit\u00e0 prima di essere messo sull&#8217;asfalto supino<\/em>&#8220;. Secondo Primicerio &#8220;<em><strong>l&#8217;avvocato Pugliese, legale dell\u2019imputata, ha estrapolato un pezzettino di quanto detto da Fineschi e lo ha decontestualizzato<\/strong><\/em>&#8220;.<\/p>\n<h3>&#8220;La telefonata prima della morte c&#8217;\u00e8 stata&#8221;<\/h3>\n<p>&#8220;<em>Il pm ha gi\u00e0 depositato memoria in cui sono rappresentati gli argomenti per i quali <strong>la telefonata nella stanza di Bergamini e realmente avvenuta<\/strong><\/em> &#8211; sostiene il pm Primicerio che replica cos\u00ec a quanto detto ieri da Pugliese, ovvero che <strong>non vi fu mai la telefonata da parte della Intern\u00f2 a Bergamini al Motel Agip<\/strong> e che sti stessi receptionist che lavoravano alla hall dissero non aver mai passato telefonate nella stanza.<\/p>\n<p>\u00ab<em><strong>P<\/strong><strong>adovano ha dichiarato che la telefonata \u00e8 giunta tra le 15 e le 15.30<\/strong><\/em>. <em>Molti testimoni hanno riscontrato che la sera stessa Padovano ha riferito ai compagni di quella telefonata. <\/em><em>Inoltre Donata Bergamini arrivata a Cosenza ha riferito che Padovano le aveva parlato di quella telefonata. <strong>E non emergono elementi di confutazione nemmeno dai receptionist in turno quel giorno<\/strong>&#8220;.\u00a0<\/em><\/p>\n<h3>&#8220;Quello che sappiamo \u00e8 che Denis Bergamini \u00e8 stato ucciso&#8221;<\/h3>\n<p>\u00c8 il turno di Fabio Anselmo legale della famiglia Bergamini profondamente indignato per le accuse contro la famiglia Bergamini <strong>la quale si \u00e8 detto nell&#8217;arringa della difensa della Intern\u00f2 abbia voluto\u00a0il processo per ragioni economiche<\/strong>: <em>&#8220;L&#8217;assicurazione cui ha fatto riferimento, avvocato Pugliese, \u00e8 scaduta. La famiglia non l&#8217;ha riattivata&#8221;<\/em>. Sulla questione droga e sul fatto che anche Domizio Bergamini indag\u00f2, Anselmo chiarisce: &#8220;<em><strong>capite la forza e la dignit\u00e0 di questa famiglia?<\/strong> Domizio Bergamini part\u00ec da Argenta e venne qui per assicurarsi di una diceria che gli era stata riferita e che si \u00e8 rivelata infondata<\/em>&#8220;.<\/p>\n<p>Un commento poi l&#8217;avvocato lo rivolge all&#8217;atteggiamento conviviale che Pugliese ha avanzato alla Corte nell&#8217;arringa di ieri: &#8220;credo che al di l\u00e0 di ogni ragionevole dubbio, sono 20 anni che faccio corte d&#8217;Assise in giro per l&#8217;Italia &#8211; conclude Anselmo -, <em><strong>mai sentito un avvocato rivolgersi ai giudici dicendo: quando sar\u00e0 finito il processo, ci vedremo.<\/strong> Non ho capito il senso di questo riferimento che a me suona proprio male. Se la Intern\u00f2 \u00e8 colpevole o innocente lo decidete voi, no il popolo, il tifo, gli affetti, <strong>ma quello che sappiamo \u00e8 che Denis Bergamini \u00e8 stato ucciso<\/strong><\/em>&#8220;.<\/p>\n<h3>Cribari: &#8220;se si dice che \u00e8 stato ammazzato, dovete dire come&#8221;<\/h3>\n<p>A prendere per ultima la parola \u00e8 l&#8217;<strong>avvocatessa Rossana Cribari, difensore di Isabella Intern\u00f2<\/strong> che continua a sostenere la versione del suicidio e l&#8217;innocenza della sua assistita. &#8220;<em>Se si dice che \u00e8 stato ammazzato, dovete dire come, cosa ha fatto, come \u00e8 stato messo sul manto stradale e come sia stato possibile che nessuno abbia visto nulla. Non ci sono testimoni. <strong>Dovevano essere almeno in due o in tre. Non ci sto dormendo la notte perch\u00e9 non capisco come potete basare il vostro convincimento su una prova scientifica che non d\u00e0 certezza<\/strong><\/em><strong>&#8220;<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Ultimo dibattimento, nella Corte D&#8217;Assise di Cosenza prima della sentenza sul processo che mira a far luce sulla morte di Denis Bergamini il calciatore del Cosenza trovato cadavere nel novembre del 1989. La Corte, presieduta dalla dottoressa Lucente emetter\u00e0 il verdetto al termine della Camera di Consiglio preceduta dalle controrepliche del procuratore D\u2019Alessio, [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":240863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-240851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=240851"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/240851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/240863"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=240851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=240851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=240851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}