{"id":241196,"date":"2024-10-05T12:00:46","date_gmt":"2024-10-05T10:00:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=241196"},"modified":"2024-10-05T09:50:52","modified_gmt":"2024-10-05T07:50:52","slug":"sportelli-linguistici-movimento-nuova-arberia-soldi-pubblici-sprecati-e-arbereshe-mortificati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sportelli-linguistici-movimento-nuova-arberia-soldi-pubblici-sprecati-e-arbereshe-mortificati\/","title":{"rendered":"Sportelli linguistici: Movimento Nuova Arb\u00ebria \u00absoldi pubblici sprecati e arb\u00ebresh\u00eb mortificati\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Polemiche e critiche nella denuncia del Movimento Federativo Nuova Arb\u00ebria a seguito <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/provincia-di-cosenza-aperti-gli-sportelli-linguistici-in-lingua-albanese-e-occitana\">dell&#8217;inaugurazione, pochi giorni fa<\/a>, degli <strong>sportelli linguistici della Provincia di Cosenza<\/strong>. \u00abI soldi pubblici vengono sprecati per mortificare gli arb\u00ebresh\u00eb e la loro plurisecolare lingua, che in Calabria si tramanda da quasi sei secoli\u00bb.<\/p>\n<p>\u00abL\u2019ente cosentino ha ottenuto un finanziamento complessivo di<strong> 92.118,62 euro<\/strong> di cui <strong>62.640,08 euro di fondi statali per l\u2019istituzione dello Sportello linguistico provinciale arb\u00ebreshe.<\/strong> Per il suo utilizzo l\u2019ente territoriale sul proprio portale istituzionale annuncia in pompa magna l\u2019istituzione di sportelli linguistici finanziati con i fondi della Legge nazionale 482\/99 per l\u2019annualit\u00e0 2023\u00bb.<\/p>\n<p>\u00abDesta scalpore \u2013 scrive il Movimento \u2013 che tale annuncio sia accompagnato da una <strong>traduzione<\/strong> in una <strong>lingua \u201calbanoide<\/strong>\u201d che calpesta e vitupera le pi\u00f9 elementari regole dell\u2019alfabeto e della grammatica dell\u2019albanese, sia di quello comune che delle variet\u00e0 arb\u00ebreshe\u00bb. Il Movimento federativo delle minoranze linguistiche Nuova Arb\u00ebria <strong>denuncia l\u2019uso improprio di fondi pubblici<\/strong> che, oltre a umiliare la lingua e cultura arb\u00ebreshe, rappresenta un forte pregiudizio in termini di tutela della nostra minoranza linguistica.<\/p>\n<p>\u00abLa qualit\u00e0 linguistica delle traduzioni pubblicate sul portale istituzionale della Provincia rivelano la pessima formazione degli addetti agli sportelli, i quali si presume che non siano stati reclutati sulla base di competenze linguistiche certificate, attesa la totale ignoranza dell\u2019alfabeto e della grammatica albanese palesata\u00bb.<\/p>\n<p>\u00abIl progetto ha anche la finalit\u00e0 di \u201cgarantire servizi di traduzione e interpretariato con supporto linguistico qualificato per le interazioni con enti pubblici, istituti scolastici, strutture sanitarie e uffici amministrativi, agevolando cos\u00ec l\u2019accesso ai servizi essenziali per i cittadini appartenenti alle minoranze linguistiche\u201d. Date le premesse, ci si chiede:<strong> in quale lingua? E con quali competenze?<\/strong> Come gli addetti allo sportello linguistico potranno \u201corganizzare corsi di lingua e cultura albanese, rivolti a tutte le fasce d\u2019et\u00e0, con l\u2019obiettivo di preservare e tramandare alle nuove generazioni la ricchezza di queste lingue e delle loro tradizioni\u201d, se gli stessi operatori ignorano le pi\u00f9 elementari regole grammaticali e ortografiche?\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Polemiche e critiche nella denuncia del Movimento Federativo Nuova Arb\u00ebria a seguito dell&#8217;inaugurazione, pochi giorni fa, degli sportelli linguistici della Provincia di Cosenza. \u00abI soldi pubblici vengono sprecati per mortificare gli arb\u00ebresh\u00eb e la loro plurisecolare lingua, che in Calabria si tramanda da quasi sei secoli\u00bb. \u00abL\u2019ente cosentino ha ottenuto un finanziamento complessivo [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":241048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-241196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/241196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=241196"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/241196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/241048"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=241196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=241196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=241196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}