{"id":241526,"date":"2024-10-09T20:39:57","date_gmt":"2024-10-09T18:39:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=241526"},"modified":"2024-10-10T07:26:26","modified_gmt":"2024-10-10T05:26:26","slug":"a-cosenza-la-fiera-del-riuso-per-vendere-e-acquistare-oggetti-da-seconda-chance","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/a-cosenza-la-fiera-del-riuso-per-vendere-e-acquistare-oggetti-da-seconda-chance\/","title":{"rendered":"A Cosenza la Fiera del Riuso: per vendere e acquistare oggetti da &#8216;seconda chance&#8217;"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Sabato 12 ottobre 2024<\/strong>, a partire dalle ore 10:00, presso Piazza Arenella a Cosenza, si svolger\u00e0 la terza edizione di<strong> &#8220;Seconda Chance&#8221;, una fiera dedicata al riutilizzo.<\/strong> Il Garage sale, organizzato dal collettivo Munnizza Social Club in collaborazione con Lotta Senza Quartiere, permetter\u00e0 a chiunque di <strong>vendere ed acquistare oggetti non pi\u00f9 necessari ma in buone condizioni<\/strong>, altrimenti destinati alla discarica, promuovendo cos\u00ec il riuso e la sostenibilit\u00e0.<\/p>\n<p>Garage sale \u00e8 il market etico che promuove il consumo responsabile. I prodotti in vendita, infatti, sono usati o come nuovi, comunque ancora utilizzabili e pronti per ricevere una seconda vita da chi potrebbe esserne interessato. Non solo, la giornata sar\u00e0 un momento di convivialit\u00e0 e coesione sociale. L&#8217;intero evento sar\u00e0, infatti, accompagnato da<strong> musica e da un pranzo sociale a cura del collettivo<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-241481 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/mercato-riuso-riciclo.jpg\" alt=\"\" width=\"481\" height=\"298\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/mercato-riuso-riciclo.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/mercato-riuso-riciclo-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/mercato-riuso-riciclo-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/mercato-riuso-riciclo-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/mercato-riuso-riciclo-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/mercato-riuso-riciclo-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/mercato-riuso-riciclo-356x220.jpg 356w\" sizes=\"auto, (max-width: 481px) 100vw, 481px\" \/><\/p>\n<p><strong>Durante la giornata saranno, inoltre, proposti tre laboratori aperti a tutti:<\/strong><\/p>\n<p><strong>LibLab<\/strong>: Un&#8217;attivit\u00e0 dedicata alla lettura e alla creativit\u00e0, condotta da Marta della libreria Raccontami. Un&#8217;occasione per stimolare l&#8217;immaginazione attraverso storie e attivit\u00e0 manuali.<br \/>\n<strong>Open Day<\/strong>: Allenamento di Boxe per Tutt*. Un allenamento di boxe aperto a tutt*, indipendentemente dall&#8217;esperienza, guidato da Carlo Stepancich. Un&#8217;opportunit\u00e0 per avvicinarsi a questo sport in un ambiente accogliente.<br \/>\n<strong>&#8220;Marionette di Munnizza&#8221;<\/strong> con Lotta senza Quartiere. Un laboratorio creativo per realizzare marionette utilizzando materiali di scarto, a cura di Christian e Teresa di Lotta senza Quartiere.<\/p>\n<p>Alla fiera saranno ammessi articoli di vario genere, tra cui abbigliamento, libri, giocattoli e piccoli mobili, purch\u00e9 idonei per una seconda vita. <strong>\u00c8 possibile prenotare uno spazio gratuito per vendere oggetti non pi\u00f9 necessari ma in buone condizioni<\/strong>, contattando il 348 9847303 o il 388 7924137.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-241541 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Fiera-del-Riuso-Cosenza.jpg\" alt=\"Fiera-del-Riuso-Cosenz\" width=\"494\" height=\"306\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Fiera-del-Riuso-Cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Fiera-del-Riuso-Cosenza-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Fiera-del-Riuso-Cosenza-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Fiera-del-Riuso-Cosenza-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Fiera-del-Riuso-Cosenza-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Fiera-del-Riuso-Cosenza-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Fiera-del-Riuso-Cosenza-356x220.jpg 356w\" sizes=\"auto, (max-width: 494px) 100vw, 494px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Sabato 12 ottobre 2024, a partire dalle ore 10:00, presso Piazza Arenella a Cosenza, si svolger\u00e0 la terza edizione di &#8220;Seconda Chance&#8221;, una fiera dedicata al riutilizzo. Il Garage sale, organizzato dal collettivo Munnizza Social Club in collaborazione con Lotta Senza Quartiere, permetter\u00e0 a chiunque di vendere ed acquistare oggetti non pi\u00f9 necessari [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":241480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-241526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/241526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=241526"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/241526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/241480"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=241526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=241526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=241526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}