{"id":241548,"date":"2024-10-10T12:00:39","date_gmt":"2024-10-10T10:00:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=241548"},"modified":"2024-10-10T12:19:59","modified_gmt":"2024-10-10T10:19:59","slug":"si-perdono-mentre-cercano-funghi-20-persone-soccorse-da-settembre-si-sottovaluta-il-pericolo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/si-perdono-mentre-cercano-funghi-20-persone-soccorse-da-settembre-si-sottovaluta-il-pericolo\/","title":{"rendered":"Funghi e boschi presi d&#8217;assalto. Tra dispersi e incidenti 20 persone soccorse in un mese \u00absi sottovaluta il pericolo\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; A caccia di funghi sottovalutando i pericoli. L&#8217;ultimo caso in ordine di tempo \u00e8 quello <a href=\"https:\/\/quicosenza.it\/news\/calabria\/dopo-la-notte-passata-nei-boschi-ritrovato-il-65enne-scomparso-mentre-andava-a-funghi-sta-bene\">di un 65enne, <\/a>che ha perso l&#8217;orientamento nel parco d&#8217;Aspromonte ed \u00e8 stato ritrovato questa mattina dopo aver trascorso la notte all&#8217;addiaccio.\u00a0<strong>Dal Pollino alla Sila, dall&#8217;Aspromonte alle Serre Vibonesi, sono diversi gli incidenti<\/strong> che puntualmente si verificano in Calabria tra la fine dell\u2019estate e l\u2019inizio dell\u2019autunno, quando <strong>migliaia di appassionati, ma anche persone senza alcuna esperienza, prendono d\u2019assalto le nostre montagne<\/strong>, avventurandosi all\u2019interno di boschi e sentieri alla ricerca di funghi.<\/p>\n<p><strong>Solo da settembre ad oggi sono stati una ventina<\/strong> i <strong>&#8220;cercatori di funghi&#8221; <\/strong>che, dopo essersi addentrati nei boschi, <strong>hanno perso l&#8217;orientamento o si sono infortunati<\/strong>. Per ritrovarli \u00e8 stato necessario attivare le ricerche di <strong>uomini e mezzi, personale del Soccorso Alpino, ma anche Vigili del fuoco, carabinieri e Protezione civile<\/strong>. Soccorritori, chiamati a soccorrere persone che, evidentemente, sfidando le insidie della montagna e <strong>non si rendono conto del pericolo che corrono<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Soccorso-Alpino-Calabria-Pollino3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-240766 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Soccorso-Alpino-Calabria-Pollino3.jpg\" alt=\"\" width=\"560\" height=\"347\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Soccorso-Alpino-Calabria-Pollino3.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Soccorso-Alpino-Calabria-Pollino3-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Soccorso-Alpino-Calabria-Pollino3-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Soccorso-Alpino-Calabria-Pollino3-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Soccorso-Alpino-Calabria-Pollino3-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Soccorso-Alpino-Calabria-Pollino3-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Soccorso-Alpino-Calabria-Pollino3-356x220.jpg 356w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<h3>La mancanza del tesserino obbligatorio<\/h3>\n<p>Senza considerare che molti fanno <a href=\"https:\/\/quicosenza.it\/news\/calabria\/funghi-a-volonta-in-calabria-ma-troppe-raccolte-selvagge-e-inesperti-e-il-tesserino-obbligatorio-e-un-miraggio\" target=\"_blank\" rel=\"noopener\">razzia di funghi <\/a>senza il tesserino (obbligatorio). Per raccogliere funghi sulle nostre montagne \u00e8\u00a0<strong>necessario ed obbligatorio avere un tesserino e che, in alcune zone, \u00e8 assolutamente vietata la raccolta, anche di un solo esemplare<\/strong>. La raccolta e commercializzazione dei funghi in Calabria \u00e8 regolamentata dalla<strong><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/09\/Funghi-legge-calabrese.pdf\">\u00a0Legge Regionale<\/a>\u00a026 novembre 2001\u00a0<\/strong>e\u00a0subordinata al possesso di una tessera nominativa amatoriale e professionale dei permessi previsti.\u00a0<strong>Tesserini amatoriale e professionale restano validi per 5 anni<\/strong>\u00a0dalla data del rilascio, previo pagamento annuale dell\u2019importo dovuto alla Regione Calabria.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Funghi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-241577 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Funghi.jpg\" alt=\"Funghi\" width=\"522\" height=\"314\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Funghi.jpg 700w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Funghi-300x180.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Funghi-698x420.jpg 698w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Funghi-150x90.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Funghi-696x419.jpg 696w\" sizes=\"auto, (max-width: 522px) 100vw, 522px\" \/><\/a><\/p>\n<h3>Da una passeggiata in cerca di funghi ad una vera emergenza<\/h3>\n<p>I boschi, specialmente in alcune zone montuose o impervie, possono essere labirinti intricati. <strong>Basta pochissimo per perdere l&#8217;orientamento mentre si \u00e8 concentrati a cercare funghi<\/strong>, magari camminando per ore senza rendersi conto della direzione in cui ci si sta muovendo. La<strong> mancanza di preparazione fisica<\/strong>, <strong>di un&#8217;adeguato abbigliamento <\/strong>(scarpe non adatte e abbigliamento troppo leggero),<strong> la pochissima conoscenza del territorio<\/strong> e l&#8217;assenza di strumentazione pu\u00f2 trasformare una tranquilla passeggiata in una vera e propria emergenza.<\/p>\n<p>Camminare<strong> su terreni scoscesi, pieni di foglie umide<\/strong>, radici sporgenti e rocce scivolose <strong>pu\u00f2 facilmente causare cadute e infortun<\/strong>i. Distorsioni, fratture e contusioni sono tra gli incidenti pi\u00f9 comuni. Spesso, chi raccoglie funghi si avventura in<strong> zone remote, lontano da strade o sentieri battuti, rendendo difficile il soccorso in caso di emergenza<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-241578 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1.jpg\" alt=\"\" width=\"519\" height=\"359\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1-300x208.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1-768x531.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1-607x420.jpg 607w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1-150x104.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1-218x150.jpg 218w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1-696x481.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Soccorso-alpino-1-100x70.jpg 100w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/a><\/p>\n<h3>&#8220;Andare a funghi prestando la massima attenzione&#8221;<\/h3>\n<p>Per questi motivi, il Soccorso Alpino e Speleologico Calabria ha inteso ribadire che \u00ab<em><strong>andare a funghi \u00e8 pericoloso e non va sottovalutato.<\/strong><\/em> <em>Spesso si riscontra la <strong>mancanza di preparazione ad affondare terreni<\/strong> che possono dimostrarsi insidiosi; oppure l&#8217;utilizzo di calzature non idonee all&#8217;ambiente che potrebbero essere causa di <strong>scivolate e successive cadute<\/strong>: non bisogna dimenticare che nella maggior parte dei casi ci si trova su terreni impervi di collina e montagna<\/em>\u00bb.<\/p>\n<p>Il Soccorso Alpino consiglia l\u2019attivazione di<a href=\"https:\/\/web.georesq.it\/\" target=\"_blank\" rel=\"noopener\"> Georesq,<\/a> un&#8217;app gratuita e progettata dal Corpo Nazionale Soccorso Alpino e Speleologico &#8211; CNSAS, promossa dal CAI &#8211; Club Alpino Italiano con il supporto del Ministero del Turismo che, <strong>durante le attivit\u00e0 outdoor<\/strong>, <strong>permette di inviare un allarme direttamente alla Centrale Operativa del CNSAS<\/strong> comunicando posizione e percorso, riducendo notevolmente i tempi di arrivo delle squadre di tecnici di soccorso.<\/p>\n<h3>Fungaioli da soli nei boschi per mantenere segreto &#8220;il posto&#8221;<\/h3>\n<p>\u00c8 frequente <strong>che i cercatori di funghi si muovano da soli per mantenere segreti i luoghi di raccolta<\/strong>; nulla di pi\u00f9 rischioso perch\u00e9 un piccolo incidente pu\u00f2 determinare situazioni difficili da controllare; ad esempio, una banale frattura pu\u00f2 irreparabilmente obbligare all&#8217;immobilit\u00e0 e alla conseguente impossibilit\u00e0 di chiamare soccorso.<\/p>\n<p>Utile pu\u00f2 essere il cellulare ma \u00e8 bene ricordare che in alcune zone montane, molte aree sono senza linea. <strong>Buona regola da non trascurare consiste nel comunicare a familiari o conoscenti il luogo e il percorso che s&#8217;intende seguire e<\/strong>\u00a0<strong>non variarlo<\/strong>. Altra buona regola \u00e8 quella di informarsi sulle condizioni metereologiche per evitare di dover fare i conti con maltempo o i temporali.\u00a0Con poche accortezze, prudenza e preparazione (e poco peso sulle spalle), si \u00e8 in grado di risolvere molti problemi. Cos\u00ec, con un po&#8217; di consapevolezza, la raccolta dei funghi potr\u00e0 essere semplicemente una ludica (e gustosa) esperienza, libera da rischi eccessivi.<\/p>\n<h3>Le principali regole da seguire<\/h3>\n<ul>\n<li>Non andare mai da soli<\/li>\n<li>Lasciare sempre detto con precisione l&#8217;itinerario che si vuole compiere, aggiornando parenti e amici di eventuali variazioni di percorso<\/li>\n<li>Consultare sempre le previsioni meteo<\/li>\n<li>Indossare scarponi e una zaino con materiale di emergenza<\/li>\n<li>In caso di pericolo chiamare il 112<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; A caccia di funghi sottovalutando i pericoli. L&#8217;ultimo caso in ordine di tempo \u00e8 quello di un 65enne, che ha perso l&#8217;orientamento nel parco d&#8217;Aspromonte ed \u00e8 stato ritrovato questa mattina dopo aver trascorso la notte all&#8217;addiaccio.\u00a0Dal Pollino alla Sila, dall&#8217;Aspromonte alle Serre Vibonesi, sono diversi gli incidenti che puntualmente si verificano in [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":241576,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-241548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/241548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=241548"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/241548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/241576"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=241548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=241548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=241548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}