{"id":24162,"date":"2013-07-09T11:02:20","date_gmt":"2013-07-09T09:02:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=24162"},"modified":"2023-01-17T13:21:42","modified_gmt":"2023-01-17T12:21:42","slug":"9684-nel-catanzarese-scoperta-una-piantagione-di-marijuana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9684-nel-catanzarese-scoperta-una-piantagione-di-marijuana\/","title":{"rendered":"Nel catanzarese scoperta una piantagione di marijuana"},"content":{"rendered":"<p style=\"text-align: justify;\">SOVERIA MANNELLI (CZ) &#8211; Scoperta dai Carabinieri della compagna di Soveria Mannelli una piantagione di canapa indiana<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">composta da oltre cento piante. I militari della stazione di Platania, guidati da un elicottero del Nucleo Elicotteri Carabinieri di Vibo Valentia, hanno individuato una piazzola di marijuana nel corso di una perlustrazione adella zona in localita&#8217; &#8220;Valle Sambate&#8221;, una zona boschiva altamente impervia. Le piante erano state messe a dimora, in un&#8217;unica piazzola, in prossimita&#8217; di un corso d&#8217;acqua che ne permetteva l&#8217;irrigazione attraverso un sistema di tubi in gomma. L&#8217;intera piantagione e&#8217; stata estirpata e distrutta sul posto insieme ai tubi utilizzati per l&#8217;irrigazione.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SOVERIA MANNELLI (CZ) &#8211; Scoperta dai Carabinieri della compagna di Soveria Mannelli una piantagione di canapa indiana<\/p>\n","protected":false},"author":22,"featured_media":24163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-24162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=24162"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/24162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/24163"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=24162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=24162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=24162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}