{"id":242699,"date":"2024-10-29T07:00:10","date_gmt":"2024-10-29T06:00:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=242699"},"modified":"2024-12-19T16:15:12","modified_gmt":"2024-12-19T15:15:12","slug":"allunical-creata-una-macchina-che-riesce-a-prevenire-gli-eventi-franosi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/allunical-creata-una-macchina-che-riesce-a-prevenire-gli-eventi-franosi\/","title":{"rendered":"Unical, ecco il simulatore di frane che prevede smottamenti e previene rischi idrogeologici"},"content":{"rendered":"<p>RENDE \u2013 Dissesto idrogeologico, frane, difesa del territorio e prevenzione. La convivenza con questi eventi \u00e8 diventata consuetudine cos\u00ec come quella con le emergenze. Una <strong>risposta concreta<\/strong> arriva dall\u2019Unical e precisamente dal Camilab il Laboratorio di Cartografia Ambientale e Modellistica Idrogeologica del Dipartimento DIMES.<\/p>\n<p>E\u2019 stato <strong>creato un vero e proprio \u201csimulatore di frane\u201d<\/strong> che rappresenta un <strong>unicum a livello internazionale<\/strong> e che permette grazie alle sue dimensioni, alla qualit\u00e0 dei sensori applicati e alla notevole flessibilit\u00e0 di utilizzo di rendere realistici scenari franosi prevedendone in anticipo le condizioni di innesco.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-242704 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-03.jpg\" alt=\"\" width=\"523\" height=\"324\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-03.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-03-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-03-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-03-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-03-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-03-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-03-356x220.jpg 356w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/><\/p>\n<h4><strong>Il modello<\/strong><\/h4>\n<p>E&#8217; stato progettato in modo da conferire al simulatore grande flessibilit\u00e0 e versatilit\u00e0 nell\u2019utilizzo. \u00c8 <strong>attrezzato di sensoristica<\/strong> per la misura delle principali grandezze fisiche che governano i processi di deformazione e di rottura, di un impianto di video registrazione, di laser per la misura degli spostamenti e di dispositivi per la valutazione delle velocit\u00e0 coinvolte. <strong>La presenza di due canali indipendenti consente<\/strong>, inoltre, <strong>di analizzare anche la fase di propagazione e di prevedere il posizionamento di strutture di impatto per valutare eventuali strategie di mitigazione.<\/strong><\/p>\n<p>\u00abGrazie a questo prototipo siamo in grado di<strong> replicare in laboratorio quello che succede nella realt\u00e0<\/strong> \u2013 dice la professoressa Giovanna Capparelli ideatrice, insieme al prof Versace, della \u201cmacchina\u201d \u2013 Analizzando i diversi tipi di terreno e simulando le piogge riusciamo a riprodurre casi reali e ad individuare le condizioni predisponenti gli eventi franosi\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-242703 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-01.jpg\" alt=\"\" width=\"531\" height=\"329\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-01.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-01-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-01-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-01-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-01-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-01-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/Unical-simulatore-Frane-01-356x220.jpg 356w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\" \/><\/p>\n<h4><strong>Il \u201csimulatore di frane\u201d<\/strong><\/h4>\n<p>D\u00e0 la possibilit\u00e0 al team dei ricercatori del Camilab di <strong>studiare condizioni estreme di pioggia e situazioni stratigrafiche anche molto complesse<\/strong> arrivando persino a raggiungere un\u2019inclinazione di 50 gradi. <strong>Sono stati analizzati grandi campioni di terreno prelevati a Sarno<\/strong>, teatro in passato di una devastante colata di fango, e oggi il Camilab presta la sua collaborazione alla<strong> task force ministeriale che si sta occupando degli smottamenti che hanno distrutto parte di Casamicciola sull\u2019isola di Ischia.<\/strong><\/p>\n<p>Gli studi svolti sulle frane, le attivit\u00e0 sviluppate grazie a questo simulatore hanno consentito al Camilab il riconoscimento di \u201cWorld Centre of Excellence on Landslide Risk Reduction 2023-2026\u201d, nell\u2019ambito dell\u2019International Consortium on Landslides, supportato da importanti organismi quali l&#8217;UNESCO, UNISDR, WMO, FAO, IUGS. <strong>Il know-how del Camilab \u00e8 a disposizione sia di enti pubblici che di attivit\u00e0 industriali impegnate nella previsione e prevenzione del rischio frana<\/strong> e di programmi di alta formazione come il master di \u201c<strong>Analisi Multirischio e Pianificazione di Protezione Civile<\/strong>\u201d di cui \u00e8 stato pubblicato il bando per il 2025.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-242702 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/unical-simulatore-di-frane-02.jpg\" alt=\"\" width=\"510\" height=\"316\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/unical-simulatore-di-frane-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/unical-simulatore-di-frane-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/unical-simulatore-di-frane-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/unical-simulatore-di-frane-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/unical-simulatore-di-frane-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/unical-simulatore-di-frane-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/10\/unical-simulatore-di-frane-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE \u2013 Dissesto idrogeologico, frane, difesa del territorio e prevenzione. La convivenza con questi eventi \u00e8 diventata consuetudine cos\u00ec come quella con le emergenze. Una risposta concreta arriva dall\u2019Unical e precisamente dal Camilab il Laboratorio di Cartografia Ambientale e Modellistica Idrogeologica del Dipartimento DIMES. E\u2019 stato creato un vero e proprio \u201csimulatore di frane\u201d che [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":242705,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[19],"class_list":["post-242699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/242699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=242699"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/242699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/242705"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=242699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=242699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=242699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}