{"id":242719,"date":"2024-10-23T16:55:00","date_gmt":"2024-10-23T14:55:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=242719"},"modified":"2024-10-23T16:55:50","modified_gmt":"2024-10-23T14:55:50","slug":"scuolabus-a-caloveto-dal-comune-garantiscono-nessun-bambino-restera-a-piedi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/scuolabus-a-caloveto-dal-comune-garantiscono-nessun-bambino-restera-a-piedi\/","title":{"rendered":"Scuolabus a Caloveto, dal Comune garantiscono \u00abnessun bambino rester\u00e0 a piedi\u00bb"},"content":{"rendered":"<p>CALOVETO (CS) &#8211; I termini per richiedere di poter usufruire del servizio Scuolabus sono scaduti ma, viste le numerose richieste, l\u2019Amministrazione Comunale, insieme agli uffici comunali competente, si sta adoperando per <strong>venire incontro alle esigenze di tutte le famiglie<\/strong>. Per questi motivi dal Comune fanno sapere che il vicesindaco Luigi Nigro si sta occupando personalmente dell\u2019organizzazione del servizio giornaliero: i <strong>genitori<\/strong> e <strong>tutori<\/strong> dei bambini frequentanti le scuole dell\u2019infanzia, primaria e secondaria di primo grado possono <strong>fare richiesta direttamente agli uffici comunali preposti. <\/strong>Il Primo Cittadino coglie l\u2019occasione per esprimere soddisfazione per le numerose adesioni che testimoniano la qualit\u00e0 del servizio di scuolabus, che garantisce spostamenti dalle utenze domestiche ai vari plessi scolastici in piena sicurezza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CALOVETO (CS) &#8211; I termini per richiedere di poter usufruire del servizio Scuolabus sono scaduti ma, viste le numerose richieste, l\u2019Amministrazione Comunale, insieme agli uffici comunali competente, si sta adoperando per venire incontro alle esigenze di tutte le famiglie. Per questi motivi dal Comune fanno sapere che il vicesindaco Luigi Nigro si sta occupando personalmente [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":242720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-242719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/242719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=242719"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/242719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/242720"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=242719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=242719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=242719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}