{"id":243251,"date":"2024-10-30T00:08:04","date_gmt":"2024-10-29T23:08:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=243251"},"modified":"2024-10-30T00:10:27","modified_gmt":"2024-10-29T23:10:27","slug":"alvini-vittoria-importante-e-un-ottimo-primo-tempo-con-un-4-e-dura-abbiamo-bisogno-dei-tifosi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/alvini-vittoria-importante-e-un-ottimo-primo-tempo-con-un-4-e-dura-abbiamo-bisogno-dei-tifosi\/","title":{"rendered":"Alvini \u201dvittoria importante e un ottimo primo tempo. Con un -4 \u00e8 dura, abbiamo bisogno dei tifosi\u201d"},"content":{"rendered":"<p>REGGIO EMILIA &#8211; <strong>Primo successo esterno della stagione<\/strong> e tre punti importantissimi dopo le ultime prestazioni che avevano lasciato un po\u2019 di amaro in bocca. Il tecnico del Cosenza Alvini commenta in sala stampa <strong>il successo contro la Reggiana<\/strong>, grazie ad un\u2019ottima gara soprattutto nel primo tempo come ha evidenziato lo stesso allenatore che non ha nascosto la sua emozione nel ritornare a Reggio Emilia.<\/p>\n<p>\u201cVittoria meritata e importantissima. Primo <strong>tempo pi\u00f9 che buono, anzi buonissimo <\/strong>per corsa, pressione, movimenti e interscambi. <strong>Male il secondo tempo, perch\u00e9 abbiamo smesso di giocare<\/strong> e dato a loro, che hanno qualit\u00e0 e giocatori di livello di poterti riprendere. Li dobbiamo migliorare ma per il resto ottima prestazione <strong>e il merito \u00e8 tutto dei ragazzi nel volerla vincere con qualche problema nel finale<\/strong>\u201d.<\/p>\n<p>Squadra stravolta? \u201cLa squadra c&#8217;\u00e8 sempre stato. Anche sabato contro la Juve Stabia, una squadra che oggi ha pareggiato con il Sassuolo, molti non l\u2019hanno letta.<strong> Per me abbiamo fatto una partita straordinaria<\/strong>, forse la migliore del campionato, meglio del secondo tempo di oggi e indipendentemente da chi gioca. Cambiano gli interpreti ma non cambiano i principi di gioco e quello che deve fare il Cosenza. <strong>Faremo di tutto per salvarci, con un -4 \u00e8 pesantissimo<\/strong>, <strong>ma come ho gi\u00e0 detto sar\u00e0 ancora pi\u00f9 bello.<\/strong> Chiusura dedicata ai tifosi: oggi sono stati straordinari, venire in 500 di marted\u00ec, sono stati fantastici. <strong>Abbiamo bisogno dei nostri tifosi, abbiamo bisogno del Marulla che ci aiuti altrimenti non ce la facciamo<\/strong>. La salita \u00e8 altissima e i ragazzi devono di sentire il calore e la spinta dei tifosi e di quell&#8217;atmosfera che c&#8217;era questa sera\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO EMILIA &#8211; Primo successo esterno della stagione e tre punti importantissimi dopo le ultime prestazioni che avevano lasciato un po\u2019 di amaro in bocca. Il tecnico del Cosenza Alvini commenta in sala stampa il successo contro la Reggiana, grazie ad un\u2019ottima gara soprattutto nel primo tempo come ha evidenziato lo stesso allenatore che non [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":243252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-243251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/243251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=243251"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/243251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/243252"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=243251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=243251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=243251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}