{"id":243362,"date":"2024-10-31T10:37:33","date_gmt":"2024-10-31T09:37:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=243362"},"modified":"2024-10-31T10:37:33","modified_gmt":"2024-10-31T09:37:33","slug":"illeciti-nella-gestione-del-carcere-di-catanzaro-in-77-rischiano-il-processo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/illeciti-nella-gestione-del-carcere-di-catanzaro-in-77-rischiano-il-processo\/","title":{"rendered":"Illeciti nella gestione del carcere di Catanzaro, in 77 rischiano il processo"},"content":{"rendered":"<p>CATANZARO &#8211; Rischiano il processo 77 persone coinvolte nell\u2019inchiesta Open Gates sui presunti illeciti nella gestione del carcere di Siano. La Dda di Catanzaro ha infatti avanzato la richiesta di rinvio a giudizio. <strong>L\u2019inizio dell\u2019udienza preliminare \u00e8 stato fissato per il prossimo 25 novembre nell\u2019aula bunker di Catanzaro davanti al gup Sara Merlini.<\/strong><\/p>\n<p>Quattro le parti offese individuate dalla Procura, si tratta del Ministero della Giustizia, del Comune di Catanzaro, dell\u2019Asp di Catanzaro e della presidenza del Consiglio dei ministri. Confermate quindi le accuse a carico degli ex vertici del carcere di Catanzaro che per la Dda avrebbero consentito che il penitenziario di massima sicurezza si trasformasse in un \u00abhotel\u00bb dove, per usare le parole di un detenuto, \u00abcomandiamo noi altri\u00bb.<\/p>\n<p>Tra le persone indagate anche l\u2019ex direttrice del carcere Angela Paravati che aveva lasciato la direzione del carcere nel settembre del 2022 dopo 12 anni. Le vengono contestati reati, che vanno dal concorso esterno in associazione per delinquere e dal falso alla falsit\u00e0 ideologica e alla corruzione. Coinvolta anche Simona Poli che ha guidato la penitenziaria nel carcere di Catanzaro dal 2018 al 2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Rischiano il processo 77 persone coinvolte nell\u2019inchiesta Open Gates sui presunti illeciti nella gestione del carcere di Siano. La Dda di Catanzaro ha infatti avanzato la richiesta di rinvio a giudizio. L\u2019inizio dell\u2019udienza preliminare \u00e8 stato fissato per il prossimo 25 novembre nell\u2019aula bunker di Catanzaro davanti al gup Sara Merlini. Quattro le [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":243187,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-243362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/243362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=243362"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/243362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/243187"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=243362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=243362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=243362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}